{"id":37012,"date":"2025-11-07T12:45:02","date_gmt":"2025-11-07T11:45:02","guid":{"rendered":"https:\/\/www.celum.com\/de\/?post_type=event&#038;p=37012"},"modified":"2026-05-08T13:48:37","modified_gmt":"2026-05-08T11:48:37","slug":"celumsummit26","status":"publish","type":"event","link":"https:\/\/www.celum.com\/de\/event\/celumsummit26\/","title":{"rendered":"CELUMsummit 26"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"37012\" class=\"elementor elementor-37012\" data-elementor-post-type=\"event\">\n\t\t\t\t<div class=\"elementor-element elementor-element-93a6c33 e-flex e-con-boxed e-con e-parent\" data-id=\"93a6c33\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3535587 e-con-full e-flex e-con e-child\" data-id=\"3535587\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5418096 e-con-full e-flex e-con e-child\" data-id=\"5418096\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b29efb elementor-widget-tablet__width-inherit elementor-widget elementor-widget-heading\" data-id=\"7b29efb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">CELUM <br>\nKunden- <br>\nKonferenz <br>\n2026<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d5f4909 e-con-full e-flex e-con e-child\" data-id=\"d5f4909\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-dbb1650 e-con-full e-flex e-con e-child\" data-id=\"dbb1650\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bed33d8 elementor-widget elementor-widget-image\" data-id=\"bed33d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"298\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/CELUMsummit26-Logo-vertical_dark-BG-1-300x298.png\" class=\"attachment-medium size-medium wp-image-37033\" alt=\"\" srcset=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/CELUMsummit26-Logo-vertical_dark-BG-1-300x298.png 300w, https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/CELUMsummit26-Logo-vertical_dark-BG-1-1024x1016.png 1024w, https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/CELUMsummit26-Logo-vertical_dark-BG-1-150x150.png 150w, https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/CELUMsummit26-Logo-vertical_dark-BG-1-768x762.png 768w, https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/CELUMsummit26-Logo-vertical_dark-BG-1-1536x1524.png 1536w, https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/CELUMsummit26-Logo-vertical_dark-BG-1.png 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8404a2b elementor-widget__width-initial elementor-absolute elementor-hidden-tablet elementor-hidden-mobile e-transform elementor-widget elementor-widget-image\" data-id=\"8404a2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Summit-top-links-1-1024x1024.png\" class=\"attachment-large size-large wp-image-37032\" alt=\"\" srcset=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Summit-top-links-1-1024x1024.png 1024w, https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Summit-top-links-1-300x300.png 300w, https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Summit-top-links-1-150x150.png 150w, https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Summit-top-links-1-768x768.png 768w, https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Summit-top-links-1.png 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-afec99e e-flex e-con-boxed e-con e-parent\" data-id=\"afec99e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-94ba7a4 elementor-widget elementor-widget-text-editor\" data-id=\"94ba7a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">NUR NOCH<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cfef5bc elementor-countdown--label-block elementor-widget elementor-widget-countdown\" data-id=\"cfef5bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"countdown.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-expire-actions=\"[{&quot;type&quot;:&quot;hide&quot;}]\" class=\"elementor-countdown-wrapper\" data-date=\"1781078400\">\n\t\t\t<div class=\"elementor-countdown-item\"><span class=\"elementor-countdown-digits elementor-countdown-days\"><\/span> <span class=\"elementor-countdown-label\">Tage<\/span><\/div><div class=\"elementor-countdown-item\"><span class=\"elementor-countdown-digits elementor-countdown-hours\"><\/span> <span class=\"elementor-countdown-label\">Stunden<\/span><\/div><div class=\"elementor-countdown-item\"><span class=\"elementor-countdown-digits elementor-countdown-minutes\"><\/span> <span class=\"elementor-countdown-label\">Minuten<\/span><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57f819a elementor-widget elementor-widget-text-editor\" data-id=\"57f819a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>BIS ZUM CELUMSUMMIT 26<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd2fbc4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"bd2fbc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1e2fd9e e-flex e-con-boxed e-con e-parent\" data-id=\"1e2fd9e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-06f3e81 e-con-full e-flex e-con e-child\" data-id=\"06f3e81\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d0f160 elementor-widget elementor-widget-text-editor\" data-id=\"1d0f160\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>10. und 11. Juni 2026<\/strong><\/p><p style=\"text-align: center;\">CELUM Campus, Passaustra\u00dfe 26-28, 4030 Linz, \u00d6sterreich<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-72ea54e e-con-full e-grid e-con e-child\" data-id=\"72ea54e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5d7cbb9 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5d7cbb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#programm\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">zum Programm<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e0550a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1e0550a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjI4NTg2IiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Zur Anmeldung<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1028422 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1028422\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM4MjY0IiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Anmeldung f\u00fcr Partner<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-30437e4 e-flex e-con-boxed e-con e-parent\" data-id=\"30437e4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e507f13 elementor-widget elementor-widget-heading\" data-id=\"e507f13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Next Generation Commerce \u2013 <\/br>\nSocial. Agentic. B2B. European.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9e3be9 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"e9e3be9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>CELUMsummit &#8211; die Konferenz<\/strong><\/p><p style=\"text-align: center;\">Verbringen wir gemeinsam zwei Tage gef\u00fcllt mit intensivem Wissenstransfer, Trainings, Erfahrungsaustausch und Networking &#8211; am 10. und 11. Juni 2026 wieder vor Ort in Linz.<\/p><p style=\"text-align: center;\">Vortr\u00e4ge in deutscher und englischer Sprache.<\/p><p style=\"text-align: center;\">Kostenlos f\u00fcr Kunden, Partner &amp; CELUM Freunde!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cdb71ee e-flex e-con-boxed e-con e-parent\" data-id=\"cdb71ee\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c05094b e-grid e-con-boxed e-con e-child\" data-id=\"c05094b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0b84820 e-flex e-con-boxed e-con e-child\" data-id=\"0b84820\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ca35332 elementor-widget elementor-widget-image\" data-id=\"ca35332\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/05\/Icon_Masterclasses.svg\" title=\"Icon_Masterclasses.svg\" alt=\"Icon_Masterclasses.svg\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47c006d elementor-widget elementor-widget-heading\" data-id=\"47c006d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"#training\">Training Sessions und Workshops<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d1c1fa elementor-widget elementor-widget-text-editor\" data-id=\"5d1c1fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Unsere CELUM Expert*innen vermitteln dir praxisnahes Wissen zu CELUM Produkten und neuen Features &#8211; auch in Hands-on Training Sessions. Laptop nicht vergessen!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-34107e5 e-flex e-con-boxed e-con e-child\" data-id=\"34107e5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ab16018 elementor-widget elementor-widget-image\" data-id=\"ab16018\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/05\/Icon_Conference_.svg\" title=\"Icon_Conference_.svg\" alt=\"Icon_Conference_.svg\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7e812f elementor-widget elementor-widget-heading\" data-id=\"e7e812f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"#konferenz\">Kundenvortr\u00e4ge und Use Case Sessions<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2170dd elementor-widget elementor-widget-text-editor\" data-id=\"a2170dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Exklusive Einblicke in die CELUM Roadmap, Use Cases und Erfolgsgeschichten unserer Kunden <strong>CLAAS, Ritter Energie, AUMA, Brau Union \u00d6sterreich und Dermapharm<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-30b238e e-flex e-con-boxed e-con e-child\" data-id=\"30b238e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ec131cf elementor-widget elementor-widget-image\" data-id=\"ec131cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2024\/02\/Icon_Partner-Training.svg\" title=\"Icon_Partner Training\" alt=\"Icon_Partner Training\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6526d37 elementor-widget elementor-widget-heading\" data-id=\"6526d37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"#partnerzertifizierung\">Partner Zertifizierungen<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48fdab8 elementor-widget elementor-widget-text-editor\" data-id=\"48fdab8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Unsere CELUM Expert*innen begleiten dich mit praxisnahen Trainings auf dem Weg zu deinen offiziellen CELUM Partner-Zertifikaten 2026 &#8211; kostenlos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"make-column-clickable-elementor elementor-element elementor-element-c741f40 e-con-full e-flex e-con e-child\" style=\"cursor: pointer;\" data-column-clickable=\"#event\" data-column-clickable-blank=\"_self\" data-id=\"c741f40\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7bb866f elementor-widget elementor-widget-image\" data-id=\"7bb866f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/05\/Icon_Party.svg\" title=\"Icon_Party.svg\" alt=\"Icon_Party.svg\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a27a583 elementor-widget elementor-widget-heading\" data-id=\"a27a583\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"#event\">Netzwerken und Socialising<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c940d02 elementor-widget elementor-widget-text-editor\" data-id=\"c940d02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nutze die Gelegenheit: Triff beim Abendevent alte Freundinnen und Freunde, lerne neue kennen und tausche dich mit Branchenkolleg*innen aus.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-84241cf e-flex e-con-boxed e-con e-parent\" data-id=\"84241cf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f217e3 elementor-widget__width-inherit elementor-widget elementor-widget-video\" data-id=\"2f217e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;autoplay&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;hosted&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/CELUMsummit-25-Recap-Video.mp4\" autoplay=\"\" loop=\"\" muted=\"muted\" controlsList=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-596d855 e-flex e-con-boxed e-con e-parent\" data-id=\"596d855\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50316cf elementor-widget elementor-widget-button\" data-id=\"50316cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#anmeldung\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Anmeldung<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a606f24 elementor-widget elementor-widget-heading\" data-id=\"a606f24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Warum du am CELUMsummit teilnehmen solltest<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e23d915 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e23d915\" data-element_type=\"section\" data-e-type=\"section\" id=\"training\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-bbc2236\" data-id=\"bbc2236\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7c0d31 elementor-widget elementor-widget-image\" data-id=\"d7c0d31\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/05\/Des-pock-ma-scho_450x450px.png\" class=\"attachment-large size-large wp-image-34979\" alt=\"\" srcset=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/05\/Des-pock-ma-scho_450x450px.png 900w, https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/05\/Des-pock-ma-scho_450x450px-300x300.png 300w, https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/05\/Des-pock-ma-scho_450x450px-150x150.png 150w, https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/05\/Des-pock-ma-scho_450x450px-768x768.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-78f9362\" data-id=\"78f9362\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b736c43 elementor-widget elementor-widget-heading\" data-id=\"b736c43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Training und Workshops<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cc57f4 elementor-widget elementor-widget-text-editor\" data-id=\"6cc57f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Unsere Trainings sind keine Frontalvortr\u00e4ge sondern behandeln echte Use Cases. Du lernst die neuesten Features kennen und selbst anzuwenden und kannst Fragen stellen, damit du das bestm\u00f6gliche aus deinem CELUM herausholen kannst.<\/p><p><strong><span style=\"color: #7ed248;\">Was erwartet dich bei den CELUM Produkt Use-Case Sessions?<\/span><\/strong><\/p><ul><li><strong>Produktupdates und Fachwissen aus erster Hand:<\/strong> Unsere Sprecher sind CELUM-Expert*innen, darunter Produktmanager*innen und Consultants, die dir die neuesten Produktupdates und Features pr\u00e4sentieren. Erhalte exklusive Einblicke in die Entwicklungen, die CELUM vorantreiben.<\/li><li><strong>Keine Theorie: <\/strong>Vergiss langweilige Pr\u00e4sentationen. Unsere Produktsessions sind praxisnah und genau auf deine Bed\u00fcrfnisse\u00a0 zugeschnitten.<\/li><li><strong>Q&amp;A: <\/strong>Stelle deine Fragen direkt an unsere Expert*innen und erhalte genau die Antworten, die dir weiterhelfen.<\/li><li><strong>Kostenlos:<\/strong>\u00a0 Die Teilnahme an den CELUM Produkt Use Case Sessions ist v\u00f6llig kostenlos! Erweitere dein Fachwissen und verbessere deine F\u00e4higkeiten, ohne einen Cent auszugeben.<\/li><\/ul><p>Bist du bereit, dein CELUM-Know-how auf das n\u00e4chste Level zu bringen? <a href=\"#anmeldung\"><strong>Dann sei dabei <\/strong><\/a>und erhalte deine Extra-Portion Fachwissen auf dem CELUMsummit 26!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-469246d elementor-widget elementor-widget-button\" data-id=\"469246d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#anmeldung\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Anmeldung zu den Gratis Trainings<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a4d8de elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a4d8de\" data-element_type=\"section\" data-e-type=\"section\" id=\"konferenz\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-47f229b\" data-id=\"47f229b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a1a842 elementor-widget elementor-widget-heading\" data-id=\"3a1a842\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Erfolgreiche Kundenprojekte im Fokus<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-924907d elementor-widget elementor-widget-text-editor\" data-id=\"924907d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wo Inspiration auf Austausch und Innovation trifft \u2013 mit Kundenvortr\u00e4gen, Fireside Chats und spannenden Einblicken von CELUM Expert*innen, Kund*innen und Partner*innen, die gemeinsam die Zukunft des Content Supply Chain Managements erkunden. Mit dabei sind z. B. die <a href=\"https:\/\/www.brauunion.at\/\" target=\"_blank\" rel=\"noopener\"><strong>Brau Union \u00d6sterreich<\/strong><\/a>, <strong><a href=\"https:\/\/www.claas.com\/\" target=\"_blank\" rel=\"noopener\">CLAAS<\/a>, <a href=\"https:\/\/ritter-energie.de\/\" target=\"_blank\" rel=\"noopener\">Ritter Energie<\/a>, <a href=\"https:\/\/www.auma.com\/de_DE\" target=\"_blank\" rel=\"noopener\">AUMA<\/a> und <a href=\"https:\/\/dermapharm.com\/de-de\/\" target=\"_blank\" rel=\"noopener\">Dermapharm<\/a><\/strong>, oder der <strong>E-Commerce Experte Thomas Leskowsky, der in seiner Keynote Tipps geben wird, wie du dich im E-Commerce 2026 richtig positionierst.\u00a0<\/strong><\/p><p><strong><span style=\"color: #7ed248;\">Was bietet dir die CELUMsummit Konferenz?<\/span><\/strong><\/p><ul><li><strong>Kundenvortr\u00e4ge und Kamingespr\u00e4che:<\/strong> Erfahre direkt von CELUM Kund*innen, wie sie ihre Projekte umgesetzt haben, welche Best Practices sie entwickelt und welche Erfahrungen sie auf ihrem Weg gemacht haben. Gewinne wertvolle Einblicke aus offenen Gespr\u00e4chen, die authentische Perspektiven auf die B\u00fchne bringen.<\/li><li><strong>CELUM Insights:<\/strong> Erhalte exklusive Einblicke von unserem F\u00fchrungsteam. CLEUMs CEO, CGO, CPO und Product Manager zeigen aktuelle Innovationen, sprechen \u00fcber strategische Entwicklungen und die n\u00e4chsten Schritte auf der CELUM Roadmap.<\/li><li><strong>Neues Wissen und Netzwerken:<\/strong> Nutze die Gelegenheit, frisches Know-How aus der Keynote <strong>&#8222;Zwischen Fundament und Hype: Wie du dich im E-Commerce 2026 richtig positionierst.&#8220; <\/strong>von <strong><a href=\"https:\/\/www.linkedin.com\/in\/e-commerce-specialist\/\" target=\"_blank\" rel=\"noopener\">Thomas Leskowsky<\/a><\/strong>, E-Commerce Experte und Gr\u00fcnder von Exvomo, mitzunehmen, Fragen zu stellen, Ideen zu diskutieren und dich mit anderen Teilnehmer*innen, Expert*innen, CELUM Partner*innen und den Menschen, die hinter den CELUM Produkten stehen, auszutauschen.<\/li><\/ul><p>Bist du bereit, Teil einer inspirierenden Community zu werden und von erstklassigem Fachwissen zu profitieren? <strong><a href=\"#anmeldung\">Dann nimm am CELUMsummit teil<\/a> <\/strong>und gestalte mit uns gemeinsam die Zukunft des Content Supply Chain Managements!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-7a7262d\" data-id=\"7a7262d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d54f30 elementor-widget elementor-widget-video\" data-id=\"7d54f30\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/05\/Test-Konferenzpics.mp4\" autoplay=\"\" loop=\"\" muted=\"muted\" controlsList=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dc5174d elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dc5174d\" data-element_type=\"section\" data-e-type=\"section\" id=\"event\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-df69c4a elementor-hidden-mobile\" data-id=\"df69c4a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a6b811 elementor-widget elementor-widget-image\" data-id=\"8a6b811\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/CELUMsummit-26_1080x1080px-1024x1024.gif\" class=\"attachment-large size-large wp-image-37023\" alt=\"\" srcset=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/CELUMsummit-26_1080x1080px-1024x1024.gif 1024w, https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/CELUMsummit-26_1080x1080px-300x300.gif 300w, https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/CELUMsummit-26_1080x1080px-150x150.gif 150w, https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/CELUMsummit-26_1080x1080px-768x768.gif 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3afe20d\" data-id=\"3afe20d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dcdca0d elementor-widget elementor-widget-heading\" data-id=\"dcdca0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Socialising beim CELUMsummit Apero<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-175d79e elementor-widget elementor-widget-text-editor\" data-id=\"175d79e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nach einem inspirierenden und intensiven ersten Summit-Tag laden wir dich zu einem entspannten Apero ein.<\/p><p>Triff Bekannte, Kund*innen, Partner*innen und Kolleg*innen \u2013 Der Abend bietet die perfekte Gelegenheit, Kontakte zu pflegen, neue Bekanntschaften zu schlie\u00dfen und den Tag in angenehmer Atmosph\u00e4re ausklingen zu lassen.<\/p><p><strong><span style=\"color: #7ed248;\">Was erwartet dich?<br \/><\/span><\/strong><\/p><ul><li><strong>Eine angenehme, entspannte Atmosph\u00e4re\u00a0<\/strong><\/li><li><strong>Gro\u00dfartige Gesellschaft<\/strong><\/li><li><strong>Ein Abend, der verbindet \u2013 und neue Energie f\u00fcr den n\u00e4chsten, inspirierenden Konferenztag schenkt.<\/strong><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5117b67 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5117b67\" data-element_type=\"section\" data-e-type=\"section\" id=\"partnerzertifizierung\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b58e93c\" data-id=\"b58e93c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f60a39 elementor-widget elementor-widget-heading\" data-id=\"2f60a39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Zertifizierungen f\u00fcr unsere Partner<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c393fe elementor-widget elementor-widget-text-editor\" data-id=\"6c393fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Hol dir dein Official CELUM Partner 2026 Zertifikat.<\/strong><\/p><p>Egal, ob du bereits CELUM Partner bist oder dich erst zertifizieren lassen m\u00f6chtest: Nimm an unseren Zertifizierungstrainings teil und sichere dir dein aktuelles Zertifikat.<\/p><p><strong><span style=\"color: #7ed248;\">Welchen Vorteil bieten dir die CELUMsummit Zertifizierungstrainings?<\/span><\/strong><\/p><ul><li>Produkt-Updates und Fachwissen direkt von CELUM Expert*innen<\/li><li>Deep-Dive Tech Sessions<\/li><li>Frage-und-Anwort-Runden<\/li><li>Sales-Sessions f\u00fcr noch mehr Produktverst\u00e4ndnis<\/li><\/ul><p>Bist du bereit, dein CELUM-Know-how zu vertiefen und dein Zertifikat zu erneuern oder neu zu erwerben? Und das <strong>ohne Kosten<\/strong> f\u00fcr die Zertifizierung? <strong>Dann melde dich an:\u00a0<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-adce408 elementor-widget elementor-widget-button\" data-id=\"adce408\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM4MjY0IiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Anmeldung zur Partnerzertifizierung<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-ae171fd\" data-id=\"ae171fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a0dcc0c elementor-widget elementor-widget-image\" data-id=\"a0dcc0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"487\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/CELUM-Official-Partner-2026-Badge.png\" class=\"attachment-large size-large wp-image-37024\" alt=\"\" srcset=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/CELUM-Official-Partner-2026-Badge.png 450w, https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/CELUM-Official-Partner-2026-Badge-277x300.png 277w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-0972fb7 e-flex e-con-boxed e-con e-parent\" data-id=\"0972fb7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6edb39d elementor-widget elementor-widget-heading\" data-id=\"6edb39d\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"Programm\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Programm<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7add6ee e-flex e-con-boxed e-con e-parent\" data-id=\"7add6ee\" data-element_type=\"container\" data-e-type=\"container\" id=\"programm\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ce3ba4 e-n-tabs-mobile elementor-widget elementor-widget-n-tabs\" data-id=\"4ce3ba4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;horizontal_scroll&quot;:&quot;disable&quot;}\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"80624548\" aria-label=\"Tabs. Open items with Enter or Space, close with Escape and navigate using the Arrow keys.\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"tag-eins\" data-tab-title-id=\"e-n-tab-title-806245481\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-806245481\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\t1. Tag - 10. Juni 2026\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"tag-zwei\" data-tab-title-id=\"e-n-tab-title-806245482\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-806245482\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\t2. Tag - 11. Juni 2026\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div id=\"e-n-tab-content-806245481\" role=\"tabpanel\" aria-labelledby=\"tag-eins\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-eef1ac4 e-con-full e-flex e-con e-child\" data-id=\"eef1ac4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db7a478 elementor-widget elementor-widget-heading\" data-id=\"db7a478\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Tag 1 - 10. Juni 2026<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8779755 elementor-widget elementor-widget-li-widgets--agenda\" data-id=\"8779755\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"li-widgets--agenda.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"li-widgets--agenda\">\n                    <div class=\"li-widgets--agenda__item 1\">\n                    <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">09:30 Uhr<\/span><\/div>\n            <div class=\"title\">Doors open<\/div>\n            <div class=\"content\">\n                                            <\/div>\n        <\/div>\n                            <\/div>\n                            <div class=\"li-widgets--agenda__item 1\">\n                    <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">10:00 Uhr<\/span><\/div>\n            <div class=\"title\">Er\u00f6ffnung<\/div>\n            <div class=\"content\">\n                                    <div class=\"speaker\">\n                        <span class=\"label\">Speaker: <\/span>\n                        Moderatorin Alexandra Vetrovsky-Brychta und Michael Kr\u00e4ftner                     <\/div>\n                                            <\/div>\n        <\/div>\n                            <\/div>\n                            <div class=\"li-widgets--agenda__item 1\">\n                    <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">10:15 Uhr<\/span><\/div>\n            <div class=\"title\">CELUM Keynote<\/div>\n            <div class=\"content\">\n                                    <div class=\"speaker\">\n                        <span class=\"label\">Speaker: <\/span>\n                        Michael Kr\u00e4ftner                    <\/div>\n                                                    <div class=\"description\"><p>Die exklusive Insights-Session\u00a0 bildet den Auftakt der Summit-Konferenz<\/p><\/div>\n                            <\/div>\n        <\/div>\n                            <\/div>\n                            <div class=\"li-widgets--agenda__item 1\">\n                    <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">11:00 Uhr<\/span><\/div>\n            <div class=\"title\">CELUM Caf\u00e9s<\/div>\n            <div class=\"content\">\n                                    <div class=\"speaker\">\n                        <span class=\"label\">Speaker: <\/span>\n                        Alexandra Vetrovsky-Brychta                    <\/div>\n                                                    <div class=\"description\"><p>CELUM Caf\u00e9: Diskutiere mit, bringe Perspektiven zusammen und erarbeite in kleinen Gruppen konkrete L\u00f6sungen. Du wechselst alle 20 Minuten die Tische und tr\u00e4gst so Ideen quer durch die Runde. Tischgastgeber*innen sammeln die Ergebnisse und die Erkenntnisse werden im Plenum pr\u00e4sentiert.<\/p><\/div>\n                            <\/div>\n        <\/div>\n                            <\/div>\n                            <div class=\"li-widgets--agenda__item 1\">\n                    <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">12:30 Uhr<\/span><\/div>\n            <div class=\"title\">Mittagspause<\/div>\n            <div class=\"content\">\n                                            <\/div>\n        <\/div>\n                            <\/div>\n                            <div class=\"li-widgets--agenda__item 1\">\n                    <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">13:30 Uhr<\/span><\/div>\n            <div class=\"title\">Energie f\u00fcr Menschen, Struktur f\u00fcr Content \u2013 Wie Ritter Energie Metadaten, Prozesse und CELUM CX zusammendenkt<\/div>\n            <div class=\"content\">\n                                    <div class=\"speaker\">\n                        <span class=\"label\">Speaker: <\/span>\n                        Isaac Kuke                    <\/div>\n                                                    <div class=\"description\"><p><strong>Wie wird aus einem DAM ein zentrales System f\u00fcr Produktdaten, Dokumentation und Content-Verteilung?<\/strong> <br \/>Im Kamingespr\u00e4ch geben Isaac Kuke von <a href=\"https:\/\/ritter-energie.de\/\" target=\"_blank\" rel=\"noopener\">Ritter Energie<\/a> und Marco Moretti (CELUM) Einblicke in einen Weg, der von der Cloud-Migration \u00fcber schlankere Metadatenstrukturen bis hin zu API-gest\u00fctzten Prozessen und neuen Automatisierungsm\u00f6glichkeiten f\u00fchrt. Im Fokus stehen dabei nicht nur klassische Assets, sondern vor allem Manuals, Kataloge und technische Produktinformationen \u2013 also genau die Inhalte, die im B2B4C-Umfeld schnell, pr\u00e4zise und zielgerichtet verf\u00fcgbar sein m\u00fcssen. Die Session zeigt, wie Ritter Energie CELUM heute bereichs\u00fcbergreifend nutzt, welche Rolle Struktur, Schnittstellen und Datenqualit\u00e4t dabei spielen und warum der enge Austausch mit CELUM CX entscheidend war, um Prozesse weiterzudenken und echten Mehrwert zu schaffen.<\/p><\/div>\n                            <\/div>\n        <\/div>\n                            <\/div>\n                            <div class=\"li-widgets--agenda__item 1\">\n                    <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">14:00 Uhr<\/span><\/div>\n            <div class=\"title\">Brau Union \u00d6sterreich - Customer Insights Session<\/div>\n            <div class=\"content\">\n                                    <div class=\"speaker\">\n                        <span class=\"label\">Speaker: <\/span>\n                        Valerie Semorad                    <\/div>\n                                                    <div class=\"description\"><p>Die <a href=\"https:\/\/www.brauunion.at\/unternehmen\/\" target=\"_blank\" rel=\"noopener\">Brau Union \u00d6sterreich<\/a> ist nicht nur eines der gr\u00f6\u00dften Getr\u00e4nkeunternehmen des Landes \u2013 sie ist auch ein Paradebeispiel f\u00fcr ein hochkomplexes Multi-Brand-Branding.\u00a0<br \/>In diesem Kamingespr\u00e4ch geben Valerie Elisabeth Semorad, Marketing Manager Regional Brands (Brau Union \u00d6sterreich) und Alexandra Vetrovsky-Brychta (CELUM) Einblicke in die Markenstrategie eines Multi-Brand-Kosmos.<\/p><\/div>\n                            <\/div>\n        <\/div>\n                            <\/div>\n                            <div class=\"li-widgets--agenda__item 1\">\n                    <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">14:30 Uhr<\/span><\/div>\n            <div class=\"title\">Gut bestellt, digital ausgespielt: Wie CLAAS Produktcontent system\u00fcbergreifend steuert<\/div>\n            <div class=\"content\">\n                                    <div class=\"speaker\">\n                        <span class=\"label\">Speaker: <\/span>\n                        Andreas Boekhoff                    <\/div>\n                                                    <div class=\"description\"><p>Wie bringt man Produktinformationen, Assets und Metadaten in einem hochkomplexen, internationalen Umfeld so zusammen, dass sie \u00fcber Systeme und Kan\u00e4le hinweg konsistent nutzbar werden und alle Zielgruppen ansprechen? <br \/>Im Kamingespr\u00e4ch gibt Andreas Boekhoff (Global IT) von <a href=\"https:\/\/www.claas.com\/\" target=\"_blank\" rel=\"noopener\">CLAAS<\/a> Einblicke in ein Setup, das weit \u00fcber klassisches DAM hinausgeht: von der Abbildung der Produkthierarchie im DAM \u00fcber die enge Verzahnung mit PIM und weiteren Systemen bis hin zur automatisierten Ausspielung in Portale und andere Kan\u00e4le. Ein weiterer Fokus liegt auf der standardisierten Content-Erstellung mit der CLAAS Fotobox und der vollautomatisierten Ausspielung im Shop. Die Session zeigt, warum saubere Metadaten und Systemlogik heute eine zentrale Grundlage f\u00fcr digitale Produktkommunikation, KI-Suche und Agentic Commerce sind.<\/p><\/div>\n                            <\/div>\n        <\/div>\n                            <\/div>\n                            <div class=\"li-widgets--agenda__item 1\">\n                    <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">15:00 Uhr<\/span><\/div>\n            <div class=\"title\">Kaffeepause<\/div>\n            <div class=\"content\">\n                                            <\/div>\n        <\/div>\n                            <\/div>\n                            <div class=\"li-widgets--agenda__item 1\">\n                    <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">15:30 Uhr<\/span><\/div>\n            <div class=\"title\">Software, die ankommt: Wie Dermapharm CELUM erfolgreich ausrollt<\/div>\n            <div class=\"content\">\n                                    <div class=\"speaker\">\n                        <span class=\"label\">Speaker: <\/span>\n                        Marcus Strobel                    <\/div>\n                                                    <div class=\"description\"><p>Bei <a href=\"https:\/\/dermapharm.com\/de-de\/\" target=\"_blank\" rel=\"noopener\">Dermapharm<\/a> wird CELUM nicht einfach ausgerollt \u2013 die Software ist in der Organisation angekommen. Im Kamingespr\u00e4ch mit Hannes Kollross gibt Marcus Strobel, Head of Ecommerce &amp; Online-Marketing bei Dermapharm, Einblicke, wie es gelungen ist, unterschiedliche Unternehmensbereiche Schritt f\u00fcr Schritt mitzunehmen, gewachsene Content-Prozesse zu hinterfragen und Abl\u00e4ufe neu aufzusetzen. Heute fragen weitere Bereiche aktiv nach CELUM, weil der Nutzen im Alltag sp\u00fcrbar ist: von digitalen Freigaben und zentral verf\u00fcgbaren Assets bis zur verl\u00e4sslichen Ausspielung an rund 90 Websites, Online-Apotheken, Au\u00dfendienst-Mitarbeiter und weitere Kan\u00e4le. Ein praxisnaher Erfahrungsbericht dar\u00fcber, warum erfolgreiche Software-Einf\u00fchrung bei den Menschen beginnt \u2013 und ohne verl\u00e4sslich funktionierende Technik nicht gelingt.<\/p><\/div>\n                            <\/div>\n        <\/div>\n                            <\/div>\n                            <div class=\"li-widgets--agenda__item 1\">\n                    <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">16:00 Uhr<\/span><\/div>\n            <div class=\"title\">Solutions for a world in motion \u2013 wie AUMA globale Marketingkommunikation mit CELUM in Bewegung bringt<\/div>\n            <div class=\"content\">\n                                    <div class=\"speaker\">\n                        <span class=\"label\">Speaker: <\/span>\n                        Michael Herbstritt                    <\/div>\n                                                    <div class=\"description\"><p><a href=\"https:\/\/www.auma.com\/de_DE\" target=\"_blank\" rel=\"noopener\">AUMA<\/a> ist international aufgestellt \u2013 mit Tochtergesellschaften, Vertretungen und Marketingteams rund um den Globus. Im Zuge eines Rebrandings entstand der Bedarf nach einem zentralen Ort, an dem aktuelle Markeninformationen, Assets und Materialien zuverl\u00e4ssig bereitgestellt werden k\u00f6nnen.<br \/>Im Kamingespr\u00e4ch mit Stefanie Kehrer zeigt Michael Herbstritt, wie AUMA mit CELUM ein Brand Portal aufgebaut hat, das internationale Teams unterst\u00fctzt \u2013 und wie daraus Schritt f\u00fcr Schritt ein umfassenderes DAM-Setup entsteht.<br \/>Eine praxisnahe Session dar\u00fcber, wie globale Marketingarbeit besser verbunden, strukturiert und in Bewegung gebracht werden kann.<\/p><\/div>\n                            <\/div>\n        <\/div>\n                            <\/div>\n                            <div class=\"li-widgets--agenda__item 1\">\n                    <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">17:00 Uhr<\/span><\/div>\n            <div class=\"title\">CELUM Product Keynote<\/div>\n            <div class=\"content\">\n                                    <div class=\"speaker\">\n                        <span class=\"label\">Speaker: <\/span>\n                        Alessandro Kurzidim                    <\/div>\n                                                    <div class=\"description\"><p>CELUM Produkt-Outlook<\/p><\/div>\n                            <\/div>\n        <\/div>\n                            <\/div>\n                            <div class=\"li-widgets--agenda__item 1\">\n                    <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">17:30 Uhr<\/span><\/div>\n            <div class=\"title\">Ergebnisse der CELUM Caf\u00e9s <\/div>\n            <div class=\"content\">\n                                                    <div class=\"description\"><p>Die Highlights aus den CELUM Caf\u00e9s: Freu dich auf frische Ideen, \u00fcberraschende Einsichten und konkrete Praxis-Tipps.<\/p><\/div>\n                            <\/div>\n        <\/div>\n                            <\/div>\n                            <div class=\"li-widgets--agenda__item 1\">\n                    <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">17:45 Uhr<\/span><\/div>\n            <div class=\"title\">Wrap-up und Ausblick auf Tag 2<\/div>\n            <div class=\"content\">\n                                    <div class=\"speaker\">\n                        <span class=\"label\">Speaker: <\/span>\n                        Moderator*in                    <\/div>\n                                            <\/div>\n        <\/div>\n                            <\/div>\n                            <div class=\"li-widgets--agenda__item 1\">\n                    <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">18:00 Uhr<\/span><\/div>\n            <div class=\"title\">CELUMsummit 26 Networking Apero<\/div>\n            <div class=\"content\">\n                                            <\/div>\n        <\/div>\n                            <\/div>\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-806245482\" role=\"tabpanel\" aria-labelledby=\"tag-zwei\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\" elementor-element elementor-element-2f1c94d e-con-full e-flex e-con e-child\" data-id=\"2f1c94d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-86e1624 elementor-widget elementor-widget-heading\" data-id=\"86e1624\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Tag 2 - 11. Juni 2026<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d32725 elementor-widget elementor-widget-li-widgets--agenda\" data-id=\"8d32725\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"li-widgets--agenda.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"li-widgets--agenda\">\n                    <div class=\"li-widgets--agenda__item 1\">\n                    <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">08:30<\/span><\/div>\n            <div class=\"title\">Einlass<\/div>\n            <div class=\"content\">\n                                            <\/div>\n        <\/div>\n                            <\/div>\n                            <div class=\"li-widgets--agenda__item two-entries\">\n                    <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">09:00 Uhr<\/span><\/div>\n            <div class=\"title\">Pimp your Frontend - Hands-on User Training<\/div>\n            <div class=\"content\">\n                                    <div class=\"speaker\">\n                        <span class=\"label\">Speaker: <\/span>\n                        Patricia Tr\u00fcbswasser                    <\/div>\n                                                    <div class=\"description\"><p><strong>Portale gestalten, User begeistern, Marken konsistent inszenieren<\/strong><\/p><p>In dieser Hands-on Session geht es ans Eingemachte: Du arbeitest direkt im System und optimierst Layouts, Typografie, Farben, Bildwelten und Widgets. Patricia, CELUM Designerin, zeigt praxisnah, wie du dein Frontend visuell aufwertest und gleichzeitig Usability und Markenwirkung verbesserst und beantwortet deine Fragen.<\/p><p><strong>Dein Nutzen:<\/strong> Du nimmst konkrete Gestaltungsideen und Best Practices mit, die du direkt in deinen eigenen Portalen umsetzen kannst. Laptop mitbringen \u2013 eigene Assets sind ebenfalls sehr willkommen.<\/p><\/div>\n                            <\/div>\n        <\/div>\n                                            <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">09:00 Uhr<\/span><\/div>\n            <div class=\"title\">Admin Training: Rollen, Berechtigungen & Single Sign-on in der CELUM Plattform<\/div>\n            <div class=\"content\">\n                                    <div class=\"speaker\">\n                        <span class=\"label\">Speaker: <\/span>\n                        Natasa Sardi                    <\/div>\n                                                    <div class=\"description\"><p>Dieses Training richtet sich an <strong>technisch versierte Admins<\/strong>, die ihr Rollen- und Berechtigungskonzept modernisieren und plattformweit sauber umsetzen m\u00f6chten.<br \/>Erfahre, wie du mit Nutzertypen das volle Potenzial plattformweiter Berechtigungen in CELUM aussch\u00f6pfst und fundierte Entscheidungen bei der Zuweisung der passenden Rollen f\u00fcr einzelne Nutzer*innen triffst. Lerne au\u00dferdem, wie du die Plattformnutzung mit Insights nachverfolgst und auswertest, und erhalte einen umfassenden \u00dcberblick \u00fcber die neuen Berechtigungsrollen in <strong>Nova<\/strong>.<br \/>Wir zeigen dir Best Practices f\u00fcr den Aufbau eines strukturierten, wartbaren Berechtigungsmodells und begleiten dich bei der Umstellung von SAML in CELUM <strong>Content<\/strong> auf eine moderne, OIDC-basierte Single-Sign-on-Strategie, die die Authentifizierung \u00fcber die gesamte <strong>CELUM Plattform<\/strong> hinweg vereinheitlicht.<br \/>Du erf\u00e4hrst, wie du dein Setup sicher, skalierbar und zukunftsf\u00e4hig gestaltest \u2013 ohne unn\u00f6tige Komplexit\u00e4t.<\/p><p><strong>Dein Nutzen: <\/strong>Du etablierst ein konsistentes Rollen- und Authentifizierungskonzept, erh\u00f6hst die Sicherheit deiner Plattform, erh\u00e4ltst einen umfassenden \u00dcberblick \u00fcber die neuen Funktionen im Rollenmanagement in CELUM Content und bereitest dein System technisch sauber auf kommende Releases vor.<\/p><\/div>\n                            <\/div>\n        <\/div>\n                            <\/div>\n                            <div class=\"li-widgets--agenda__item two-entries\">\n                    <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">09:45 Uhr<\/span><\/div>\n            <div class=\"title\">User Training - CELUM Experience und Content Templates<\/div>\n            <div class=\"content\">\n                                    <div class=\"speaker\">\n                        <span class=\"label\">Speaker: <\/span>\n                        Steve Lourdesamy                    <\/div>\n                                                    <div class=\"description\"><p>In dieser praxisnahen Session steigst du direkt in <strong>CELUM Experience<\/strong> ein und erstellst wirkungsvolle<strong> Content Templates,<\/strong> die deine Produktion effizienter machen, Nutzer*innen klare Orientierung geben und daf\u00fcr sorgen, dass alle Inhalte konsequent markenkonform bleiben. Wir schauen uns an, wie Templates sinnvoll aufgebaut werden, wie du hilfreiche Anleitungen integrierst und flexible Vorlagen entwickelst, mit denen Teams konsistenten Content in gro\u00dfem Umfang erstellen k\u00f6nnen.<\/p><p>Steve zeigt dir anhand praktischer Beispiele und Best Practices, wie du wirkungsvolle Templates gestaltest und sie reibungslos in deiner Organisation ausrollst. Zum Abschluss bekommst du au\u00dferdem einen ersten Einblick in die neuesten CELUM Features und wie sie deine Content-Prozesse weiter verbessern k\u00f6nnen.<\/p><p><strong>Dein Nutzen: <\/strong>Du gehst mit konkreten Ideen f\u00fcr sofort einsetzbare Content Templates, bew\u00e4hrten Methoden und neuer Inspiration f\u00fcr deinen Content-Erstellungsprozess aus dieser Session.<\/p><p><strong>Bitte bring deinen Laptop mit \u2013 und gern auch Beispiele f\u00fcr Inhalte, die du k\u00fcnftig als Template abbilden m\u00f6chtest.<\/strong><\/p><\/div>\n                            <\/div>\n        <\/div>\n                                            <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">09:45 Uhr<\/span><\/div>\n            <div class=\"title\">Admin Training: REST API & Integrationen \u2013 CELUM in der Systemlandschaft\u00a0<\/div>\n            <div class=\"content\">\n                                    <div class=\"speaker\">\n                        <span class=\"label\">Speaker: <\/span>\n                        Stefan Hasse                    <\/div>\n                                                    <div class=\"description\"><p>Dieses Training richtet sich an technisch versierte Admins und Integrationsverantwortliche, die CELUM \u00fcber die REST API professionell in bestehende IT-Landschaften \u2013 insbesondere PIM-, CMS- oder Commerce-Systeme \u2013 einbinden m\u00f6chten.<br \/>Im Fokus stehen typische Integrationsszenarien aus der Praxis sowie technische Best Practices f\u00fcr stabile, skalierbare und updatef\u00e4hige Anbindungen.<\/p><p>Wir beleuchten Architektur\u00fcberlegungen, Hosting-Aspekte und zeigen, worauf es bei nachhaltigen REST-basierten Integrationen wirklich ankommt.<br \/>Dabei teilen wir Erfahrungen aus Integrationen im Kunden- und Partnerumfeld \u2013 inklusive typischer Stolpersteine und Empfehlungen aus Engineering und Consulting.<\/p><p><strong>Dein Nutzen:<\/strong> Du verstehst, wie du CELUM sauber in deine Anwendungslandschaft integrierst, REST-basierte Anbindungen stabil aufsetzt und dein Setup technisch wie wirtschaftlich nachhaltig betreibst.<\/p><p><strong>Bitte nimm deinen Laptop zu diesem Training mit!<\/strong><\/p><\/div>\n                            <\/div>\n        <\/div>\n                            <\/div>\n                            <div class=\"li-widgets--agenda__item 1\">\n                    <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">10:30 Uhr<\/span><\/div>\n            <div class=\"title\">Kaffeepause<\/div>\n            <div class=\"content\">\n                                            <\/div>\n        <\/div>\n                            <\/div>\n                            <div class=\"li-widgets--agenda__item two-entries\">\n                    <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">11:00 Uhr<\/span><\/div>\n            <div class=\"title\">User Training: Mehr Tempo, Transparenz und strukturierte Zusammenarbeit mit CELUM Work<\/div>\n            <div class=\"content\">\n                                    <div class=\"speaker\">\n                        <span class=\"label\">Speaker: <\/span>\n                        Magdalena Mayer, Patricia Tr\u00fcbswasser, Isabel Stingl                    <\/div>\n                                                    <div class=\"description\"><p>Die Trainingssession f\u00fcr effiziente Workflows und Zusammenarbeit. Du lernst, wie CELUM Work dich bei der Planung, Umsetzung und Freigabe von Content unterst\u00fctzt. Du erf\u00e4hrst, wie Workflows aufgebaut sind, wie Aufgaben transparent gesteuert werden und wie Teams effizient zusammenarbeiten \u2013 auch abteilungs\u00fcbergreifend und mit externen Projektbeteiligten.<\/p><p>Reale Beispiele aus den CELUM Design- und Marketing-Teams zeigen, wie Work im Alltag eingesetzt wird.<\/p><p><strong>Dein Nutzen:<\/strong> Du bringst Struktur, Transparenz und Nachvollziehbarkeit in deine Prozesse, reduzierst Abstimmungsschleifen und beschleunigst Time-to-Market.<\/p><\/div>\n                            <\/div>\n        <\/div>\n                                            <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">11:00 Uhr<\/span><\/div>\n            <div class=\"title\">Marketing Workshop: Sichtbar bleiben im KI-Zeitalter<\/div>\n            <div class=\"content\">\n                                    <div class=\"speaker\">\n                        <span class=\"label\">Speaker: <\/span>\n                        Jan K\u00f6nigst\u00e4tter                    <\/div>\n                                                    <div class=\"description\"><p>KI-basierte Systeme ver\u00e4ndern radikal, wie Inhalte gefunden und ausgew\u00e4hlt werden. Wie stellst du sicher, dass deine Marke und Produkte auch in einem Umfeld aus SEO, Agentic Commerce und KI-getriebenen Plattformen sichtbar bleiben?<\/p><p>In diesem Workshop zeigt SEO-Experte Jan K\u00f6nigst\u00e4tter (<a href=\"https:\/\/www.otago.at\/\" target=\"_blank\" rel=\"noopener\">otago<\/a>), wie GEO (Generative Engine Optimisation), konsistentes Storytelling und datengetriebene Markenarbeit E Commerce Teams helfen, ihre Sichtbarkeit gezielt f\u00fcr eine KI getriebene Zukunft auszurichten. Du erh\u00e4ltst klare Handlungsempfehlungen und Praxisbeispiele, wie du deine Content Strategie auf neue, KI basierte Ausspielmechanismen optimierst.<\/p><p>Damit diese Strategien wirken, braucht es sauber strukturierte Inhalte: Stephan N\u00f6stler von CELUM zeigt, wie ein durchdachtes Metadatenkonzept sicherstellt, dass KI Systeme deine Produkte korrekt interpretieren \u2013 und warum strukturierte Content Basisarbeit heute ebenso entscheidend ist wie GEO.<\/p><p><strong>Dein Nutzen: <\/strong>Du lernst, wie sich Sichtbarkeit ver\u00e4ndert und wie du Inhalte, Produkte und Markeninformationen so vorbereitest, dass sie von KI Systemen gefunden, bewertet und ausgew\u00e4hlt werden.<\/p><\/div>\n                            <\/div>\n        <\/div>\n                            <\/div>\n                            <div class=\"li-widgets--agenda__item two-entries\">\n                    <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">11:45 Uhr<\/span><\/div>\n            <div class=\"title\">User Training: Effizient arbeiten mit CELUM Content<\/div>\n            <div class=\"content\">\n                                    <div class=\"speaker\">\n                        <span class=\"label\">Speaker: <\/span>\n                        Reinhard Eisl                    <\/div>\n                                                    <div class=\"description\"><p>In diesem interaktiven Training bekommst du Einblick in die neuen M\u00f6glichkeiten von CELUM Content 26.7. Im Fokus stehen die Standard- KI-Funktionen, NOVA-UI und die Weiterentwicklung nach dem Ende der Advanced UI.<\/p><p><strong>Dein Nutzen: <\/strong>Du verstehst nicht nur, was neu ist \u2013 sondern wie du Nova UI und die KI-Funktionen sofort produktiv einsetzt, um Effizienz, Qualit\u00e4t und Geschwindigkeit in deinem Content-Management sp\u00fcrbar zu steigern.<\/p><\/div>\n                            <\/div>\n        <\/div>\n                                            <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">11:45 Uhr<\/span><\/div>\n            <div class=\"title\">Admin Training: CELUM Content<\/div>\n            <div class=\"content\">\n                                    <div class=\"speaker\">\n                        <span class=\"label\">Speaker: <\/span>\n                        Georg Payreder                    <\/div>\n                                                    <div class=\"description\"><p>Dieses Admin Training geht einen Schritt tiefer: Du erf\u00e4hrst, wie Content-Modelle aufgebaut werden und wie du CELUM Content langfristig stabil und erweiterbar aufsetzt.<\/p><p><strong>Dein Nutzen:<\/strong> Du legst das technische und strukturelle Fundament f\u00fcr nachhaltiges Content Management \u2013 auch bei komplexen Produktportfolios und internationalen Anforderungen.<\/p><\/div>\n                            <\/div>\n        <\/div>\n                            <\/div>\n                            <div class=\"li-widgets--agenda__item 1\">\n                    <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">12:30<\/span><\/div>\n            <div class=\"title\">kurze Pause<\/div>\n            <div class=\"content\">\n                                            <\/div>\n        <\/div>\n                            <\/div>\n                            <div class=\"li-widgets--agenda__item 1\">\n                    <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">12:45<\/span><\/div>\n            <div class=\"title\">Zwischen Fundament und Hype: Wie du dich im E-Commerce 2026 richtig positionierst.<\/div>\n            <div class=\"content\">\n                                    <div class=\"speaker\">\n                        <span class=\"label\">Speaker: <\/span>\n                        Thomas Leskowsky                    <\/div>\n                                                    <div class=\"description\"><p>E-Commerce 2026 ist voller neuer M\u00f6glichkeiten \u2013 aber auch voller Buzzwords, Hypes und Unsicherheiten. Zwischen Social Commerce, Agentic Search und Agentic Commerce stellt sich f\u00fcr viele Unternehmen die entscheidende Frage: Was davon ist wirklich relevant f\u00fcr mein Business \u2013 und was nicht?<\/p><p>In dieser Keynote liefert dir Thomas Orientierung in einem Markt, der sich rasant ver\u00e4ndert. Er zeigt, welche Grundlagen du heute unbedingt im Griff haben solltest, wie aktuelle Trendthemen realistisch einzuordnen sind und warum nicht jeder neue Hype automatisch strategische Relevanz hat. Dabei verbindet er Marktbeobachtung mit klarer Einordnung und gibt dir wertvolle Impulse, wie du deine Marke, deine Produkte und deine digitalen Kan\u00e4le im E-Commerce 2026 gezielt weiterentwickeln kannst.<\/p><p><a href=\"https:\/\/www.linkedin.com\/in\/e-commerce-specialist\/\" target=\"_blank\" rel=\"noopener\">Thomas Leskowsky<\/a> ist Gr\u00fcnder von exvomo und E-Commerce-Spezialist mit Fokus auf praxisnahe Weiterbildung, Community-Aufbau und strategische Beratung f\u00fcr H\u00e4ndler*innen und Dienstleister. Mit Erfahrung aus dem Exit seines Onlineshops SH\u00d6PY sowie seiner Arbeit in Beratung und Eventorganisation bringt er frische Perspektiven und fundiertes Know-how in die \u00f6sterreichische E-Commerce-Szene.<\/p><\/div>\n                            <\/div>\n        <\/div>\n                            <\/div>\n                            <div class=\"li-widgets--agenda__item 1\">\n                    <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">13:15<\/span><\/div>\n            <div class=\"title\">CELUMsummit 26 Wrap-up<\/div>\n            <div class=\"content\">\n                                    <div class=\"speaker\">\n                        <span class=\"label\">Speaker: <\/span>\n                        Michael Kr\u00e4ftner und Alexandra Vetrovsky-Brychta                    <\/div>\n                                            <\/div>\n        <\/div>\n                            <\/div>\n                            <div class=\"li-widgets--agenda__item 1\">\n                    <div class=\"li-widgets--agenda__entry\">\n            <div class=\"time\"><span class=\"text\">13:30 Uhr<\/span><\/div>\n            <div class=\"title\">Ende der Konferenz<\/div>\n            <div class=\"content\">\n                                            <\/div>\n        <\/div>\n                            <\/div>\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c0084fb e-flex e-con-boxed e-con e-parent\" data-id=\"c0084fb\" data-element_type=\"container\" data-e-type=\"container\" id=\"anmeldung\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cca30ea elementor-widget elementor-widget-heading\" data-id=\"cca30ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Jetzt Anmelden<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c18973 e-grid e-con-full e-con e-child\" data-id=\"1c18973\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bce5683 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"bce5683\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjI4NTg2IiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Anmeldung<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cdfbac4 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"cdfbac4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM4MjY0IiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Anmeldung f\u00fcr Partner<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-23274d5 e-flex e-con-boxed e-con e-parent\" data-id=\"23274d5\" data-element_type=\"container\" data-e-type=\"container\" id=\"sprecher\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-85bd709 elementor-widget elementor-widget-heading\" data-id=\"85bd709\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vortragende<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3fe2a87 e-grid e-con-boxed e-con e-child\" data-id=\"3fe2a87\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-73b0303 e-flex e-con-boxed e-con e-child\" data-id=\"73b0303\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a3c97e4 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"a3c97e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/elementor\/thumbs\/aboekhoff-rlqo8s3r4v8riqejbk6tzsn23ipcib2pe0b0ihkb6o.png\" title=\"aboekhoff\" alt=\"Andeas Boekhoff - CLAAS\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3eefe2 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"c3eefe2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Andreas Boekhoff<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a20425 elementor-widget elementor-widget-text-editor\" data-id=\"4a20425\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Application Developer \/ Consultant\u00a0<br \/>CLAAS<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-378674f e-con-full e-flex e-con e-child\" data-id=\"378674f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ba31aa elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"3ba31aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/elementor\/thumbs\/Isaac-Kuke_Ritter-Energie-rm172r9oxylstahc45g4lssbeguombwbfq5gmmeeg0.jpg\" title=\"Isaac Kuke_Ritter Energie\" alt=\"Isaac Kuke_Ritter Energie\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6be63cd elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"6be63cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Isaac Kuke<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09cc166 elementor-widget elementor-widget-text-editor\" data-id=\"09cc166\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Teamleiter Digitales Informationsmanagement<br \/>Ritter Energie<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ba6ccee e-con-full e-flex e-con e-child\" data-id=\"ba6ccee\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a92924b elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"a92924b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/elementor\/thumbs\/Valerie_Semorad_500px-rmmefvtcca71m8m1n0p3316xy5vmzy2b2o7tz7uysg.jpg\" title=\"Valerie Semorad &#8211; Brau Union \u00d6sterreich500px\" alt=\"Valerie Semorad - Brau Union \u00d6sterreich500px\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93298bd elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"93298bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Valerie Semorad<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-157b969 elementor-widget elementor-widget-text-editor\" data-id=\"157b969\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Marketing Manager<br \/>Regional Brands<br \/>Brau Union \u00d6sterreich <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0f0a293 e-con-full e-flex e-con e-child\" data-id=\"0f0a293\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50e3b77 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"50e3b77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/elementor\/thumbs\/Marcus-Strobel_Dermapharm-rmmefvtcca71m8m1n0p3316xy5vmzy2b2o7tz7uysg.jpeg\" title=\"Marcus Strobel &#8211; Dermapharm\" alt=\"Marcus Strobel - Dermapharm\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca60552 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"ca60552\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Marcus Strobel <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3108fb7 elementor-widget elementor-widget-text-editor\" data-id=\"3108fb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Head of Ecommerce &amp;<br \/>Online-Marketing<br \/>Dermapharm\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ec6d741 e-con-full e-flex e-con e-child\" data-id=\"ec6d741\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2804ca1 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"2804ca1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/elementor\/thumbs\/Michael-Herbstritt_AUMA_800px-rmmefuvi5g5ramnesiagijfhcs09s8ykqjkchxwcyo.png\" title=\"Michael-Herbstritt_AUMA_800px\" alt=\"Michael-Herbstritt_AUMA_800px\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a970e5a elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"a970e5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Michael Herbstritt<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e24b17c elementor-widget elementor-widget-text-editor\" data-id=\"e24b17c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">SHS | Marketing<br \/>AUMA Riester GmbH\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ed84feb e-con-full e-flex e-con e-child\" data-id=\"ed84feb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-831b1c1 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"831b1c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/elementor\/thumbs\/Profilfoto-Thomas-Leskowsky_800px-rl0rx18fv306f5m90y31szn47o4yogbtsvyq80v5pc.png\" title=\"Profilfoto-Thomas-Leskowsky_800px\" alt=\"Thomas Leskowsky\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7c1197 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"d7c1197\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Thomas Leskowsky <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c24fd0e elementor-widget elementor-widget-text-editor\" data-id=\"c24fd0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Gr\u00fcnder Exvomo und\u00a0<br \/>E-Commerce Specialist\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a0fdfe6 e-con-full e-flex e-con e-child\" data-id=\"a0fdfe6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b9a14c2 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"b9a14c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/elementor\/thumbs\/Koenigstaetter-Jan-business-500x500-1-ren9mgcargjamvk7s96i037ji6r8i2whkswoyjxzts.png\" title=\"K\u00f6nigst\u00e4tter-Jan-business-500&#215;500\" alt=\"K\u00f6nigst\u00e4tter-Jan-business-500x500\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0e9d7f elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"b0e9d7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Jan K\u00f6nigst\u00e4tter<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90b85dd elementor-widget elementor-widget-text-editor\" data-id=\"90b85dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Eigent\u00fcmer<br \/>Otago Online Consulting<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7663141 e-con-full e-flex e-con e-child\" data-id=\"7663141\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a8efa1 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"2a8efa1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/elementor\/thumbs\/Michael-J.-Kraeftner_Founder-and-CEO_CELUM_800x800px-r6f2n0zqs4yutaeyxy4p873fpufv1cttpg2jdi04v4.jpg\" title=\"Michael-J.-Kraeftner_Founder-and-CEO_CELUM_800x800px.jpg\" alt=\"Michael-J.-Kraeftner_Founder-and-CEO_CELUM_800x800px.jpg\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-258bf4e elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"258bf4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Michael J. Kr\u00e4ftner<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfda335 elementor-widget elementor-widget-text-editor\" data-id=\"dfda335\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Gr\u00fcnder und CEO<br \/>CELUM<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1abef97 e-con-full e-flex e-con e-child\" data-id=\"1abef97\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7808608 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"7808608\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/elementor\/thumbs\/Alexandra-Vetrovsky-Brychta_CGO_CELUM-2024-263-Business-Portait-r6f2n0zqs4yutaeyxy4p873fpufv1cttpg2jdi04v4.jpg\" title=\"Alexandra-Vetrovsky-Brychta_CGO_CELUM-2024-263-Business-Portait.jpg\" alt=\"Alexandra-Vetrovsky-Brychta_CGO_CELUM-2024-263-Business-Portait.jpg\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49ec385 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"49ec385\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Alexandra Vetrovsky-Brychta<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af8c4b3 elementor-widget elementor-widget-text-editor\" data-id=\"af8c4b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Chief Growth Officer<br \/>CELUM\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7f24ece e-con-full e-flex e-con e-child\" data-id=\"7f24ece\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-88d0834 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"88d0834\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/elementor\/thumbs\/Alessandro-Kurzidim_CPO_CELUM-r6f2n1xkyz054wdlsgjbsouwb8b891xk1kq0uryqow.jpg\" title=\"Alessandro-Kurzidim_CPO_CELUM.jpg\" alt=\"Alessandro-Kurzidim_CPO_CELUM.jpg\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-649d751 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"649d751\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Alessandro Kurzidim<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ff55ef elementor-widget elementor-widget-text-editor\" data-id=\"4ff55ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Chief Product Officer<br \/>CELUM<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8874709 e-con-full e-flex e-con e-child\" data-id=\"8874709\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-86ab712 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"86ab712\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/elementor\/thumbs\/Natasa-Sardi_CEUM_800x800p-r6f2vcu9cadbowbfb1qotlfh7rdy8sw76o6fgrnjq8.jpg\" title=\"Natasa-Sardi_CEUM_800x800p\" alt=\"Natasa-Sardi_CEUM_800x800p\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cffc478 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"cffc478\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Natasa Sardi<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6150825 elementor-widget elementor-widget-text-editor\" data-id=\"6150825\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Product Manager<br \/>CELUM<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c1dbb4d e-flex e-con-boxed e-con e-child\" data-id=\"c1dbb4d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-fc5a15a e-con-full e-flex e-con e-child\" data-id=\"fc5a15a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4aad5fc elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"4aad5fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/elementor\/thumbs\/Steve-Lourdesamy_CELUM_800x800p-r6f2w35qnndcpz971d48resdujs88bsomag0wikiw0.jpg\" title=\"Steve-Lourdesamy_CELUM_800x800p\" alt=\"Steve-Lourdesamy_CELUM_800x800p\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63cad1e elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"63cad1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Steve Lourdesamy<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c42fca elementor-widget elementor-widget-text-editor\" data-id=\"8c42fca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Product Manager<br \/>CELUM\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3226e54 e-con-full e-flex e-con e-child\" data-id=\"3226e54\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8bbc632 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"8bbc632\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/elementor\/thumbs\/Magdalena-Mayer_800px-rlqo8r5wy17h74fwh1s7favli4tzalyz1vnj17lpcw.png\" title=\"Magdalena-Mayer_800px\" alt=\"Magdalena Mayer, Product Manager CELUM Work\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae83614 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"ae83614\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Magdalena Mayer<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97468b0 elementor-widget elementor-widget-text-editor\" data-id=\"97468b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Product Manager<br \/>CELUM\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6c31797 e-con-full e-flex e-con e-child\" data-id=\"6c31797\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e0fc1fc elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"e0fc1fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/elementor\/thumbs\/Reinhard-Eisl_CELUM_800px-r6f2vrvodmxwunpkv88pxhmupxbtnyjwkqm75718yo.jpg\" title=\"Reinhard-Eisl_CELUM_800px\" alt=\"Reinhard-Eisl_CELUM_800px\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b3b337 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"3b3b337\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Reinhard Eisl<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbb168f elementor-widget elementor-widget-text-editor\" data-id=\"dbb168f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Senior Product Manager<br \/>CELUM<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-03050c7 e-con-full e-flex e-con e-child\" data-id=\"03050c7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7952785 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"7952785\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/elementor\/thumbs\/Robert-Hoeller-CELUM-rlqo8b6npullpr342cvjqwwrel0qnr7jbok9vi9eao.png\" title=\"Robert H\u00f6ller-CELUM\" alt=\"Robert H\u00f6ller-CELUM\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34865d7 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"34865d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Robert H\u00f6ller<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9382be9 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"9382be9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Business Consultant &amp; CISO<br \/>CELUM\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a06bcb e-flex e-con-boxed e-con e-child\" data-id=\"3a06bcb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-189a137 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"189a137\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/elementor\/thumbs\/Patricia-Photo-riplhfx67rhncojfxha63caqhwlt1af52g207ie84g.jpg\" title=\"Patricia Tr\u00fcbswasser\" alt=\"Patricia Tr\u00fcbswasser, Designerin bei CELUM\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e88075 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"8e88075\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Patricia Tr\u00fcbswasser<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ed4461 elementor-widget elementor-widget-text-editor\" data-id=\"9ed4461\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Designerin<br \/>CELUM\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-390a9e9 e-con-full e-flex e-con e-child\" data-id=\"390a9e9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e1b949d elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"e1b949d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/elementor\/thumbs\/GPA1_square-pde261s22o2b3se5f2xnznvhrmhsght6kfs9qmbrmo.jpg\" title=\"GPA1_square\" alt=\"Georg Payreder\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cba5422 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"cba5422\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Georg Payreder<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1265a47 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"1265a47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Team Lead Technical Sales<br \/>CELUM\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ed2ede e-con-full e-flex e-con e-child\" data-id=\"3ed2ede\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22a34bd elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"22a34bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/elementor\/thumbs\/Stefan-Hasse_800px-qhf2tme2n2bsrrwy7hbwv0d7fh2meuuxu3i6cn4s68.jpg\" title=\"Stefan Hasse\" alt=\"Stefan Hasse\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c46fcdc elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"c46fcdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Stefan Hasse<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-747bff6 elementor-widget elementor-widget-text-editor\" data-id=\"747bff6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Development Consultant<br \/>CELUM\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b777b14 e-con-full e-flex e-con e-child\" data-id=\"b777b14\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c7bdc6 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"1c7bdc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/elementor\/thumbs\/Marco-Moretti_800px_web-rke9yoe7k5ev2xracl4dohzqjjyshuo98f6vzw921s.png\" title=\"Marco Moretti\" alt=\"Marco Moretti\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4072add elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"4072add\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Marco Moretti<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37730ad elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"37730ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Customer Experience Manager<br \/>CELUM\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-172395a e-con-full e-flex e-con e-child\" data-id=\"172395a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5369767 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"5369767\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/elementor\/thumbs\/Stefanie-Kehrer_800px-r2ihhk0tjsw0zk7vkcy423qgoyauxlm7bw4qwdxw9s.jpg\" title=\"Stefanie Kehrer_800px\" alt=\"Stefanie Kehrer, Partner Manager, CELUM\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dd6b1a elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"1dd6b1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Stefanie Kehrer<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-243530d elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"243530d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Partner Manager<br \/>CELUM\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f415ed1 e-flex e-con-boxed e-con e-parent\" data-id=\"f415ed1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0def307 elementor-widget elementor-widget-heading\" data-id=\"0def307\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unsere CELUMsummit Partner<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ac26dee e-grid e-con-full e-con e-child\" data-id=\"ac26dee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5367dc2 elementor-widget elementor-widget-image\" data-id=\"5367dc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.communicode.com\/de-de\/partner\/celum\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"420\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/Kopie-von-Grey-border-for-white-background-images-1024x538.png\" class=\"attachment-large size-large wp-image-38552\" alt=\"\" srcset=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/Kopie-von-Grey-border-for-white-background-images-1024x538.png 1024w, https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/Kopie-von-Grey-border-for-white-background-images-300x158.png 300w, https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/Kopie-von-Grey-border-for-white-background-images-768x403.png 768w, https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/Kopie-von-Grey-border-for-white-background-images.png 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4718409 elementor-widget elementor-widget-image\" data-id=\"4718409\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/netcare.de\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"420\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/Partner-CELUMsummit-26-netcare-1024x538.png\" class=\"attachment-large size-large wp-image-38559\" alt=\"\" srcset=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/Partner-CELUMsummit-26-netcare-1024x538.png 1024w, https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/Partner-CELUMsummit-26-netcare-300x158.png 300w, https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/Partner-CELUMsummit-26-netcare-768x403.png 768w, https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/Partner-CELUMsummit-26-netcare.png 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a1c480 elementor-widget elementor-widget-image\" data-id=\"6a1c480\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.brix.ch\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"420\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/partner-CELUMsummit-26-1024x538.png\" class=\"attachment-large size-large wp-image-38553\" alt=\"\" srcset=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/partner-CELUMsummit-26-1024x538.png 1024w, https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/partner-CELUMsummit-26-300x158.png 300w, https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/partner-CELUMsummit-26-768x403.png 768w, https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/partner-CELUMsummit-26.png 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3753de1 e-flex e-con-boxed e-con e-parent\" data-id=\"3753de1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-adb858f elementor-widget elementor-widget-heading\" data-id=\"adb858f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Reiseplanung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2496ad elementor-widget elementor-widget-menu-anchor\" data-id=\"f2496ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"reiseplanung\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3e53532 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3e53532\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-8f8199d\" data-id=\"8f8199d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a24b85 elementor-widget elementor-widget-image\" data-id=\"9a24b85\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/elementor\/thumbs\/Flughafen-Linz-r6f2n3tbipbkg60x55agp3iwjny9hruzzmled0xt78.jpg\" title=\"Flughafen-Linz.jpg\" alt=\"Flughafen-Linz.jpg\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f816dfd\" data-id=\"f816dfd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-da79397 elementor-widget elementor-widget-heading\" data-id=\"da79397\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Anreise nach Linz<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88cee15 elementor-widget elementor-widget-text-editor\" data-id=\"88cee15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Linz, die Hauptstadt von Ober\u00f6sterreich, liegt eingebettet in eine wundersch\u00f6ne Naturlandschaft an den Ufern der Donau.\u00a0Linz ist eine Stadt der Kultur, Industrie und Natur, Kulturhauptstadt Europas 2009 und UNESCO City of Media Arts. Die Stadt ist ideal gelegen und kann mit allen Verkehrsmitteln schnell und einfach erreicht werden.<br \/><a href=\"https:\/\/www.linztourismus.at\/assets\/Stadtplan_2023_DE_RZ.pdf\">Stadtplan als pdf zum Herunterladen<\/a><\/p><p><strong>Entspannt mit der Bahn nach Linz reisen:<\/strong><br \/>Der Linzer Hauptbahnhof liegt mitten im Zentrum und ist direkt an alle \u00f6ffentlichen Verkehrsmittel angebunden.<br \/><a href=\"https:\/\/www.linztourismus.at\/freizeit\/reise-planen\/anreise\/bahn\">Reiseplanung mit dem Zug<\/a><\/p><p><strong>Mit dem Flugzeug nach Linz reisen:<\/strong><br \/>Der Linz Airport liegt vor den Toren der Stadt in H\u00f6rsching. In etwa 20 Minuten ist das Stadtzentrum vom Flughafen aus erreichbar.\u00a0<br \/><a href=\"https:\/\/www.linztourismus.at\/freizeit\/reise-planen\/anreise\/flughafen-linz\">Details zur Anreise mit dem Flugzeug<\/a><\/p><p><strong>Linz ist mit dem Auto von allen Himmelsrichtungen aus gut erreichbar:<\/strong><br \/><a href=\"https:\/\/www.linztourismus.at\/freizeit\/reise-planen\/anreise\/auto\">Routenplanung mit dem Auto<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1906a4d elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1906a4d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-36a043a\" data-id=\"36a043a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16a07a7 elementor-widget elementor-widget-heading\" data-id=\"16a07a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hotels in Linz<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a8b0ed elementor-widget elementor-widget-text-editor\" data-id=\"4a8b0ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Um dir die Planung deines Aufenthalts in Linz zu erleichtern, haben wir hier ein paar Hotels aufgelistet. Nat\u00fcrlich verf\u00fcgt die Stadt Linz noch \u00fcber viele weitere Unterk\u00fcnfte. Die gro\u00dfen Hotelbuchungsplattformen wie Booking.com oder Trivago geben dir einen umfassenden \u00dcberblick.<\/p><p><strong>Hotels:<\/strong><\/p><p><a href=\"https:\/\/www.motel-one.com\/de\/hotels\/linz\/hotel-linz-hauptplatz\/Courtyard\">Motel One Linz Hauptplatz<\/a><br \/><a href=\"http:\/\/www.hotelamdomplatz.at\/\">Hotel am Domplatz<\/a><br \/><a href=\"https:\/\/all.accor.com\/hotel\/0519\/index.de.shtml\">Hotel Ibis Styles Linz<\/a><br \/><a href=\"https:\/\/www.bestwestern.at\/hotels\/Linz\/Best-Western-Hotel-Spinnerei\/hotel\">Best Western Hotel Spinnerei<\/a>\u00a0<br \/><a href=\"https:\/\/www.radissonhotels.com\/de-de\/hotels\/park-inn-linz\">Park Inn by Radisson<\/a><br \/><a href=\"https:\/\/www.wyndhamhotels.com\/de-de\/trademark\/linz-austria\/amedia-linz-trademark-collection\/overview\">Amedia Linz, Trademark Collection by Wyndham<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-0d7e7ea\" data-id=\"0d7e7ea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24793cc elementor-widget elementor-widget-image\" data-id=\"24793cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/elementor\/thumbs\/IMG_CELUM_Hotel-stay-r6f2n3tbipbkg60x55agp3iwjny9hruzzmled0xt78.png\" title=\"IMG_CELUM_Hotel-stay.png\" alt=\"IMG_CELUM_Hotel-stay.png\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-94e8989 e-flex e-con-boxed e-con e-parent\" data-id=\"94e8989\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-399fdb2 elementor-widget elementor-widget-image\" data-id=\"399fdb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/5064577.fs1.hubspotusercontent-na1.net\/hubfs\/5064577\/Events\/CELUMsummit%2026%20-%20Save%20the%20date.ics\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"79\" src=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Button_save-the-date_big-300x79.jpg\" class=\"attachment-medium size-medium wp-image-37049\" alt=\"\" srcset=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Button_save-the-date_big-300x79.jpg 300w, https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Button_save-the-date_big.jpg 648w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>CELUM Kunden- Konferenz 2026 NUR NOCH Tage Stunden Minuten BIS ZUM CELUMSUMMIT 26 10. und 11. Juni 2026 CELUM Campus, Passaustra\u00dfe 26-28, 4030 Linz, \u00d6sterreich zum Programm Zur Anmeldung Anmeldung f\u00fcr Partner Next Generation Commerce \u2013 Social. Agentic. B2B. European. CELUMsummit &#8211; die Konferenz Verbringen wir gemeinsam zwei Tage gef\u00fcllt mit intensivem Wissenstransfer, Trainings, Erfahrungsaustausch [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":37068,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-37012","event","type-event","status-publish","has-post-thumbnail","hentry","event_category-conferences-seminars"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.6 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>CELUMsummit 26<\/title>\n<meta name=\"description\" content=\"Sei beim CELUMsummit 26 am 10. und 11.. Juni in Linz dabei! Melde dich an und erfahre das Neueste aus der CELUM-Welt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.celum.com\/de\/event\/celumsummit26\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CELUMsummit 26\" \/>\n<meta property=\"og:description\" content=\"Sei beim CELUMsummit 26 am 10. und 11.. Juni in Linz dabei! Melde dich an und erfahre das Neueste aus der CELUM-Welt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.celum.com\/de\/event\/celumsummit26\/\" \/>\n<meta property=\"og:site_name\" content=\"Celum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/celumcorporate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T11:48:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/CELUMsummit-26_DE_1200x630px.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CELUM\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"33\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.celum.com\\\/de\\\/event\\\/celumsummit26\\\/\",\"url\":\"https:\\\/\\\/www.celum.com\\\/de\\\/event\\\/celumsummit26\\\/\",\"name\":\"CELUMsummit 26\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.celum.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.celum.com\\\/de\\\/event\\\/celumsummit26\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.celum.com\\\/de\\\/event\\\/celumsummit26\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.celum.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/11\\\/CELUMsummit-26_DE_1200x630px.jpg\",\"datePublished\":\"2025-11-07T11:45:02+00:00\",\"dateModified\":\"2026-05-08T11:48:37+00:00\",\"description\":\"Sei beim CELUMsummit 26 am 10. und 11.. Juni in Linz dabei! Melde dich an und erfahre das Neueste aus der CELUM-Welt.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.celum.com\\\/de\\\/event\\\/celumsummit26\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.celum.com\\\/de\\\/event\\\/celumsummit26\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.celum.com\\\/de\\\/event\\\/celumsummit26\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.celum.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/11\\\/CELUMsummit-26_DE_1200x630px.jpg\",\"contentUrl\":\"https:\\\/\\\/www.celum.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/11\\\/CELUMsummit-26_DE_1200x630px.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.celum.com\\\/de\\\/event\\\/celumsummit26\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Events\",\"item\":\"https:\\\/\\\/www.celum.com\\\/de\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CELUMsummit 26\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.celum.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.celum.com\\\/de\\\/\",\"name\":\"CELUM\",\"description\":\"Make Brands. Sell Products.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.celum.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.celum.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.celum.com\\\/de\\\/#organization\",\"name\":\"CELUM\",\"url\":\"https:\\\/\\\/www.celum.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.celum.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.celum.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/01\\\/celum-header-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.celum.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/01\\\/celum-header-logo.svg\",\"width\":1,\"height\":1,\"caption\":\"CELUM\"},\"image\":{\"@id\":\"https:\\\/\\\/www.celum.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/celumcorporate\\\/\",\"https:\\\/\\\/x.com\\\/CELUM\",\"https:\\\/\\\/www.instagram.com\\\/celum_life\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/328144\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/celumTV\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"CELUMsummit 26","description":"Sei beim CELUMsummit 26 am 10. und 11.. Juni in Linz dabei! Melde dich an und erfahre das Neueste aus der CELUM-Welt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.celum.com\/de\/event\/celumsummit26\/","og_locale":"de_DE","og_type":"article","og_title":"CELUMsummit 26","og_description":"Sei beim CELUMsummit 26 am 10. und 11.. Juni in Linz dabei! Melde dich an und erfahre das Neueste aus der CELUM-Welt.","og_url":"https:\/\/www.celum.com\/de\/event\/celumsummit26\/","og_site_name":"Celum","article_publisher":"https:\/\/www.facebook.com\/celumcorporate\/","article_modified_time":"2026-05-08T11:48:37+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/CELUMsummit-26_DE_1200x630px.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CELUM","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"33\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.celum.com\/de\/event\/celumsummit26\/","url":"https:\/\/www.celum.com\/de\/event\/celumsummit26\/","name":"CELUMsummit 26","isPartOf":{"@id":"https:\/\/www.celum.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.celum.com\/de\/event\/celumsummit26\/#primaryimage"},"image":{"@id":"https:\/\/www.celum.com\/de\/event\/celumsummit26\/#primaryimage"},"thumbnailUrl":"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/CELUMsummit-26_DE_1200x630px.jpg","datePublished":"2025-11-07T11:45:02+00:00","dateModified":"2026-05-08T11:48:37+00:00","description":"Sei beim CELUMsummit 26 am 10. und 11.. Juni in Linz dabei! Melde dich an und erfahre das Neueste aus der CELUM-Welt.","breadcrumb":{"@id":"https:\/\/www.celum.com\/de\/event\/celumsummit26\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.celum.com\/de\/event\/celumsummit26\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.celum.com\/de\/event\/celumsummit26\/#primaryimage","url":"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/CELUMsummit-26_DE_1200x630px.jpg","contentUrl":"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/CELUMsummit-26_DE_1200x630px.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.celum.com\/de\/event\/celumsummit26\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Events","item":"https:\/\/www.celum.com\/de\/events\/"},{"@type":"ListItem","position":2,"name":"CELUMsummit 26"}]},{"@type":"WebSite","@id":"https:\/\/www.celum.com\/de\/#website","url":"https:\/\/www.celum.com\/de\/","name":"CELUM","description":"Make Brands. Sell Products.","publisher":{"@id":"https:\/\/www.celum.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.celum.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.celum.com\/de\/#organization","name":"CELUM","url":"https:\/\/www.celum.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.celum.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2021\/01\/celum-header-logo.svg","contentUrl":"https:\/\/www.celum.com\/de\/wp-content\/uploads\/sites\/3\/2021\/01\/celum-header-logo.svg","width":1,"height":1,"caption":"CELUM"},"image":{"@id":"https:\/\/www.celum.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/celumcorporate\/","https:\/\/x.com\/CELUM","https:\/\/www.instagram.com\/celum_life\/","https:\/\/www.linkedin.com\/company\/328144\/","https:\/\/www.youtube.com\/user\/celumTV\/"]}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.celum.com\/de\/wp-json\/wp\/v2\/event\/37012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.celum.com\/de\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.celum.com\/de\/wp-json\/wp\/v2\/types\/event"}],"author":[{"embeddable":true,"href":"https:\/\/www.celum.com\/de\/wp-json\/wp\/v2\/users\/17"}],"version-history":[{"count":20,"href":"https:\/\/www.celum.com\/de\/wp-json\/wp\/v2\/event\/37012\/revisions"}],"predecessor-version":[{"id":38927,"href":"https:\/\/www.celum.com\/de\/wp-json\/wp\/v2\/event\/37012\/revisions\/38927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.celum.com\/de\/wp-json\/wp\/v2\/media\/37068"}],"wp:attachment":[{"href":"https:\/\/www.celum.com\/de\/wp-json\/wp\/v2\/media?parent=37012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}