{"id":45357,"date":"2025-05-19T10:18:21","date_gmt":"2025-05-19T08:18:21","guid":{"rendered":"https:\/\/www.celum.com\/en\/?page_id=45357"},"modified":"2025-12-30T15:30:58","modified_gmt":"2025-12-30T14:30:58","slug":"manage-brands-and-their-stories","status":"publish","type":"page","link":"https:\/\/www.celum.com\/en\/manage-brands-and-their-stories\/","title":{"rendered":"Manage brands and their stories"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"45357\" class=\"elementor elementor-45357\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ea0653 elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ea0653\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ef0bcfe\" data-id=\"ef0bcfe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3af48c elementor-widget__width-auto elementor-absolute elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"a3af48c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"273\" src=\"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2023\/05\/NEW-Dark.svg\" class=\"attachment-medium size-medium wp-image-30910\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7eb1d7 elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"c7eb1d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Challenge<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2c7b97 elementor-widget elementor-widget-heading\" data-id=\"f2c7b97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Manage brands and their stories<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0383d0 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"a0383d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tBuild brand equity \u2013 tell your brand story to inspire employees, ecosystem and, most importantly, customers.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9a066f elementor-align-left celum-button celum-button--secondary elementor-widget elementor-widget-button\" data-id=\"b9a066f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.celum.com\/en\/demo\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">book a demo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61bfcaa elementor-widget__width-auto elementor-absolute elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"61bfcaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"273\" src=\"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2023\/05\/NEW-Dark.svg\" class=\"attachment-medium size-medium wp-image-30910\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-18237c7\" data-id=\"18237c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c25f7b7 elementor-widget elementor-widget-image\" data-id=\"c25f7b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"449\" src=\"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2025\/04\/ILLU_Brand_Management_illustration_for_primary_blue_BG-1024x575.png\" class=\"attachment-large size-large wp-image-46475\" alt=\"\" srcset=\"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2025\/04\/ILLU_Brand_Management_illustration_for_primary_blue_BG-1024x575.png 1024w, https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2025\/04\/ILLU_Brand_Management_illustration_for_primary_blue_BG-300x168.png 300w, https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2025\/04\/ILLU_Brand_Management_illustration_for_primary_blue_BG-768x431.png 768w, https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2025\/04\/ILLU_Brand_Management_illustration_for_primary_blue_BG-1536x863.png 1536w, https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2025\/04\/ILLU_Brand_Management_illustration_for_primary_blue_BG-2048x1150.png 2048w, https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2025\/04\/ILLU_Brand_Management_illustration_for_primary_blue_BG-1920x1078.png 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f022564 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f022564\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4ed82ff\" data-id=\"4ed82ff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c345b8f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c345b8f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-dc76d4a\" data-id=\"dc76d4a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7189f9 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"d7189f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"128px\" height=\"128px\" viewBox=\"0 0 128 128\"><title>Icon_tools<\/title><g id=\"Icon_tools\" stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g id=\"Group-61\" transform=\"translate(21.859351, 14.827895)\" stroke-width=\"4\"><line x1=\"30.9661792\" y1=\"18.5262524\" x2=\"45.7691792\" y2=\"44.1652524\" id=\"Stroke-153\" stroke=\"#005682\"><\/line><line x1=\"38.7205792\" y1=\"55.9572524\" x2=\"20.5735792\" y2=\"24.5262524\" id=\"Stroke-155\" stroke=\"#005682\"><\/line><path d=\"M52.9904792,56.6733524 L70.9664792,87.8083524 C72.6234792,90.6783524 71.6394792,94.3473524 68.7704792,96.0043524 C65.9004792,97.6613524 62.2304792,96.6783524 60.5734792,93.8083524 L46.0504792,68.6523524\" id=\"Stroke-157\" stroke=\"#005682\"><\/path><path d=\"M34.0294792,0.521852401 L39.9764792,10.8228524 C40.2674792,11.3258524 40.0884792,11.9738524 39.5764792,12.2698524 L1.59347922,34.1998524 C0.768479221,34.6758524 -0.209520779,33.9318524 0.0394792214,33.0218524 L4.54747922,16.6848524 C4.62247922,16.4138524 4.80247922,16.1808524 5.04847922,16.0388524 L32.5764792,0.145852401 C33.0884792,-0.150147599 33.7384792,0.0188524013 34.0294792,0.521852401\" id=\"Stroke-159\" stroke=\"#01A9CA\"><\/path><path d=\"M65.1206792,35.4460524 L30.5476792,95.3280524 C28.8906792,98.1980524 25.2216792,99.1810524 22.3516792,97.5240524 C19.4816792,95.8670524 18.4986792,92.1980524 20.1556792,89.3280524 L54.8546792,29.2280524\" id=\"Stroke-161\" stroke=\"#005682\"><\/path><path d=\"M58.6700792,32.7248524 C51.8680792,28.3458524 49.2270792,19.3978524 52.5940792,12.0388524 C55.4660792,5.7638524 61.6070792,2.2538524 67.9020792,2.3518524 C68.2770792,2.3588524 68.5030792,2.7788524 68.3160792,3.1038524 L62.6550792,12.9088524 C62.3650792,13.4098524 62.5370792,14.0518524 63.0390792,14.3418524 L73.8130792,20.5618524 C74.3150792,20.8518524 74.9570792,20.6798524 75.2460792,20.1778524 L80.9060792,10.3748524 C81.0940792,10.0498524 81.5730792,10.0348524 81.7660792,10.3568524 C84.7500792,15.3238524 85.0200792,21.7238524 81.9120792,27.1068524 C77.2160792,35.2408524 66.6500792,37.8608524 58.6700792,32.7248524 Z\" id=\"Stroke-163\" stroke=\"#01A9CA\"><\/path><\/g><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1de4482 elementor-widget elementor-widget-heading\" data-id=\"1de4482\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">The Challenge<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db7fb02 elementor-widget elementor-widget-text-editor\" data-id=\"db7fb02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Your brand story deserves to be told like Coca Cola or Red Bull, but your budget is missing a zero&#8230; or five. You need to explain the story behind your brand as much as you need to explain the application of branding features. And above all, you want to empower brand users to achieve as much as possible without compromising brand consistency. All of this for perhaps not one, but a dozen brands.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-4c3a044 e-flex e-con-boxed e-con e-parent\" data-id=\"4c3a044\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cab3dfc elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"cab3dfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"128px\" height=\"128px\" viewBox=\"0 0 128 128\"><title>Icon_light bulb<\/title><g id=\"Icon_light-bulb\" stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g id=\"Group\" transform=\"translate(15.000000, 12.000000)\" stroke-width=\"4\"><g id=\"Group-13\" transform=\"translate(24.000000, 25.000000)\"><g id=\"Group-43\" transform=\"translate(9.000000, 22.252488)\"><path d=\"M28,35.7848501 L28,52.5626279 C28,54.0047047 27.4154829,55.3102603 26.4704465,56.2552966 C25.5254102,57.2003329 24.2198546,57.7848501 22.7777778,57.7848501 L22.7777778,57.7848501 L7.22222222,57.7848501 C5.78014538,57.7848501 4.47458982,57.2003329 3.52955348,56.2552966 C2.58451713,55.3102603 2,54.0047047 2,52.5626279 L2,52.5626279 L2,35.7848501 L28,35.7848501 Z\" id=\"Rectangle\" stroke=\"#01A9CA\"><\/path><path d=\"M12.1649425,34.408854 C12.1649425,29.9023773 12.1649425,26.8524091 12.1649425,25.2589494 C12.1649425,11.9693018 12.7640806,5.76091338 12.1649425,4.18735794 C10.9092453,0.889438055 8.29109541,-0.766285159 4.99939474,0.343889434 C1.70769406,1.45406403 0.330758707,5.82661236 2.99619429,8.86786052 C5.66162988,11.9091087 14.1938023,11.9091087 16.232402,11.9091087\" id=\"Path-13\" stroke=\"#005682\"><\/path><path d=\"M25.1649425,34.408854 C25.1649425,29.9023773 25.1649425,26.8524091 25.1649425,25.2589494 C25.1649425,11.9693018 25.7640806,5.76091338 25.1649425,4.18735794 C23.9092453,0.889438055 21.2910954,-0.766285159 17.9993947,0.343889434 C14.7076941,1.45406403 13.3307587,5.82661236 15.9961943,8.86786052 C18.6616299,11.9091087 27.1938023,11.9091087 29.232402,11.9091087\" id=\"Path-13\" stroke=\"#005682\" transform=\"translate(21.911059, 17.204427) scale(-1, 1) translate(-21.911059, -17.204427) \"><\/path><\/g><g id=\"Group-8\" stroke=\"#01A9CA\"><path d=\"M24,0 C28.9784143,0.175991263 33.6821661,1.62539259 38.1112554,4.34820398 C44.7548894,8.43242107 46.9836975,13.9480472 48.2744301,19.0457467 C49.5651626,24.1434462 49.6272915,30.1355468 45.7071918,39.0373377 C43.0937919,44.971865 39.5724943,51.0691632 35.1432989,57.3292323\" id=\"Path-32\"><\/path><path d=\"M0,0 C4.97841429,0.175991263 9.68216609,1.62539259 14.1112554,4.34820398 C20.7548894,8.43242107 22.9836975,13.9480472 24.2744301,19.0457467 C25.5651626,24.1434462 25.6272915,30.1355468 21.7071918,39.0373377 C19.0937919,44.971865 15.5724943,51.0691632 11.1432989,57.3292323\" id=\"Path-32-Copy\" transform=\"translate(12.531542, 28.664616) scale(-1, 1) translate(-12.531542, -28.664616) \"><\/path><\/g><\/g><line x1=\"83.8230416\" y1=\"30.0186061\" x2=\"91.7125164\" y2=\"25.3981612\" id=\"Path-5-Copy-26\" stroke=\"#01A9CA\" stroke-linecap=\"round\"><\/line><line x1=\"83.8230416\" y1=\"74.0186061\" x2=\"91.7125164\" y2=\"69.3981612\" id=\"Path-5-Copy-31\" stroke=\"#01A9CA\" stroke-linecap=\"round\" transform=\"translate(87.767779, 71.708384) scale(1, -1) translate(-87.767779, -71.708384) \"><\/line><line x1=\"5.82304161\" y1=\"30.0186061\" x2=\"13.7125164\" y2=\"25.3981612\" id=\"Path-5-Copy-27\" stroke=\"#01A9CA\" stroke-linecap=\"round\" transform=\"translate(9.767779, 27.708384) scale(-1, 1) translate(-9.767779, -27.708384) \"><\/line><line x1=\"89\" y1=\"49.5311609\" x2=\"98.1423048\" y2=\"49.6340466\" id=\"Path-5-Copy-28\" stroke=\"#005682\" stroke-linecap=\"round\"><\/line><line x1=\"0\" y1=\"49.5311609\" x2=\"9.14230485\" y2=\"49.6340466\" id=\"Path-5-Copy-29\" stroke=\"#005682\" stroke-linecap=\"round\"><\/line><line x1=\"29.0669299\" y1=\"14.9866224\" x2=\"24.446485\" y2=\"7.0971476\" id=\"Path-5-Copy-24\" stroke=\"#005682\" stroke-linecap=\"round\"><\/line><line x1=\"48.3087173\" y1=\"9.14230485\" x2=\"48.411603\" y2=\"0\" id=\"Path-5\" stroke=\"#01A9CA\" stroke-linecap=\"round\"><\/line><line x1=\"5.82304161\" y1=\"74.0186061\" x2=\"13.7125164\" y2=\"69.3981612\" id=\"Path-5-Copy-30\" stroke=\"#01A9CA\" stroke-linecap=\"round\" transform=\"translate(9.767779, 71.708384) scale(-1, -1) translate(-9.767779, -71.708384) \"><\/line><line x1=\"69.379705\" y1=\"14.5945408\" x2=\"73.7625998\" y2=\"6.57066668\" id=\"Path-5-Copy-21\" stroke=\"#005682\" stroke-linecap=\"round\"><\/line><\/g><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbc41f1 elementor-widget elementor-widget-heading\" data-id=\"fbc41f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our Solution<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8f17a9e elementor-reverse-mobile elementor-reverse-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f17a9e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-920abaa\" data-id=\"920abaa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a7cb044 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a7cb044\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-a7a112b\" data-id=\"a7a112b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b1f075 elementor-widget elementor-widget-text-editor\" data-id=\"7b1f075\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\" data-pm-slice=\"1 1 []\"><strong data-renderer-mark=\"true\">Turn your people into brand ambassadors.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1492bd elementor-widget elementor-widget-text-editor\" data-id=\"b1492bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tGive people an easy way to learn about your brand story and tools to apply your brand features to the content they need \u2013 always on brand.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c76298d\" data-id=\"c76298d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a5d086 elementor-widget elementor-widget-li-widgets--animations\" data-id=\"5a5d086\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"li-widgets--animations.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"li-widgets--animations\" data-sources='{\"lg\":\"https:\\\/\\\/www.celum.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/UI-Animation_Design-Themes-2.mp4\",\"md\":\"https:\\\/\\\/www.celum.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/UI-Animation_Design-Themes-2.mp4\",\"sm\":\"https:\\\/\\\/www.celum.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/UI-Animation_Design-Themes-2.mp4\",\"xs\":\"https:\\\/\\\/www.celum.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/UI-Animation_Design-Themes-2.mp4\"}'><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f4d9150 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f4d9150\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8330861\" data-id=\"8330861\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-068e44c elementor-widget elementor-widget-li-widgets--animations\" data-id=\"068e44c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"li-widgets--animations.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"li-widgets--animations\" data-sources='{\"lg\":\"https:\\\/\\\/www.celum.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/UI-Animation_embed-CT-into-Portal.mp4?ver=1761310898\",\"md\":\"https:\\\/\\\/www.celum.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/UI-Animation_embed-CT-into-Portal.mp4?ver=1761310898\",\"sm\":\"https:\\\/\\\/www.celum.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/UI-Animation_embed-CT-into-Portal.mp4?ver=1761310898\",\"xs\":\"https:\\\/\\\/www.celum.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/UI-Animation_embed-CT-into-Portal.mp4?ver=1761310898\"}'><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c9a1f66\" data-id=\"c9a1f66\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41d4f45 elementor-widget elementor-widget-text-editor\" data-id=\"41d4f45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\" data-pm-slice=\"1 1 [&quot;table&quot;,{&quot;displayMode&quot;:null,&quot;isNumberColumnEnabled&quot;:false,&quot;layout&quot;:&quot;default&quot;,&quot;localId&quot;:&quot;71393974-6550-4fa1-9bb2-95fb532bf502&quot;,&quot;width&quot;:760,&quot;__autoSize&quot;:false},&quot;tableRow&quot;,null,&quot;tableHeader&quot;,{&quot;colspan&quot;:1,&quot;rowspan&quot;:1,&quot;colwidth&quot;:null,&quot;background&quot;:null}]\"><strong data-renderer-mark=\"true\">Explain once, use often.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26e9234 elementor-widget elementor-widget-text-editor\" data-id=\"26e9234\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tBuild beautiful, intuitive brand guidelines with just a few clicks and ensure that creative partners use your branding features as intended.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e5dfac2 elementor-reverse-mobile elementor-reverse-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e5dfac2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-00f3970\" data-id=\"00f3970\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-10092ac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10092ac\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-85c28a0\" data-id=\"85c28a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10a824f elementor-widget elementor-widget-text-editor\" data-id=\"10a824f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\" data-pm-slice=\"1 1 [&quot;table&quot;,{&quot;displayMode&quot;:null,&quot;isNumberColumnEnabled&quot;:false,&quot;layout&quot;:&quot;default&quot;,&quot;localId&quot;:&quot;71393974-6550-4fa1-9bb2-95fb532bf502&quot;,&quot;width&quot;:760,&quot;__autoSize&quot;:false},&quot;tableRow&quot;,null,&quot;tableHeader&quot;,{&quot;colspan&quot;:1,&quot;rowspan&quot;:1,&quot;colwidth&quot;:null,&quot;background&quot;:null}]\"><strong data-renderer-mark=\"true\">Inject employer branding into your company\u2019s business DNA.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5fc7ce elementor-widget elementor-widget-text-editor\" data-id=\"e5fc7ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tProvide a place for your employees to learn about your brand story and share it with their colleagues, friends and families, in any language they need.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b798a99\" data-id=\"b798a99\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4fabfc elementor-widget elementor-widget-image\" data-id=\"e4fabfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"548\" src=\"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2024\/05\/UI-2-1024x701.png\" class=\"attachment-large size-large wp-image-40777\" alt=\"Centralise all brand management activities into one application, and create a single source of truth for all brand management efforts.\" srcset=\"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2024\/05\/UI-2-1024x701.png 1024w, https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2024\/05\/UI-2-300x205.png 300w, https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2024\/05\/UI-2-768x526.png 768w, https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2024\/05\/UI-2-1536x1052.png 1536w, https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2024\/05\/UI-2-2048x1402.png 2048w, https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2024\/05\/UI-2-1920x1315.png 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-12b6cc1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"12b6cc1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-45bf6e3\" data-id=\"45bf6e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a1e56cf elementor-widget elementor-widget-li-widgets--animations\" data-id=\"a1e56cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"li-widgets--animations.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"li-widgets--animations\" data-sources='{\"lg\":\"https:\\\/\\\/www.celum.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/UI-Animation_Frontend-Green-mg-with-asset-gallery.mp4\",\"md\":\"https:\\\/\\\/www.celum.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/UI-Animation_Frontend-Green-mg-with-asset-gallery.mp4\",\"sm\":\"https:\\\/\\\/www.celum.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/UI-Animation_Frontend-Green-mg-with-asset-gallery.mp4\",\"xs\":\"https:\\\/\\\/www.celum.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/UI-Animation_Frontend-Green-mg-with-asset-gallery.mp4\"}'><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5c3e6c0\" data-id=\"5c3e6c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66bc4c4 elementor-widget elementor-widget-text-editor\" data-id=\"66bc4c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\" data-pm-slice=\"1 1 [&quot;table&quot;,{&quot;displayMode&quot;:null,&quot;isNumberColumnEnabled&quot;:false,&quot;layout&quot;:&quot;default&quot;,&quot;localId&quot;:&quot;71393974-6550-4fa1-9bb2-95fb532bf502&quot;,&quot;width&quot;:760,&quot;__autoSize&quot;:false},&quot;tableRow&quot;,null,&quot;tableHeader&quot;,{&quot;colspan&quot;:1,&quot;rowspan&quot;:1,&quot;colwidth&quot;:null,&quot;background&quot;:null}]\"><strong data-renderer-mark=\"true\">Reach out and let your brand story run free.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f143f4e elementor-widget elementor-widget-text-editor\" data-id=\"f143f4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tCreate press and media portals for your entire organisation or just a single event in minutes \u2013 build meaningful relationships with press, media and influencers on any channel.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc780f7 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc780f7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3278a1e\" data-id=\"3278a1e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-811afa9 elementor-widget elementor-widget-text-editor\" data-id=\"811afa9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>See CELUM in Action<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-e9e020b\" data-id=\"e9e020b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7aeae02 elementor-widget elementor-widget-text-editor\" data-id=\"7aeae02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Learn more what CELUM can do for you. Take a deeper dive into the features and get answers to all your questions.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47a07ba elementor-align-left celum-button celum-button--secondary elementor-widget elementor-widget-button\" data-id=\"47a07ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.celum.com\/en\/demo\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Book a Demo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-551778d elementor-absolute elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"551778d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2021\/03\/NEW-Dark.svg\" class=\"attachment-medium size-medium wp-image-7524\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c48527a elementor-widget__width-auto elementor-absolute elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"c48527a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2021\/03\/NEW-Dark.svg\" class=\"attachment-medium size-medium wp-image-7524\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ec6102 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6ec6102\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6b95446\" data-id=\"6b95446\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c15841 elementor-widget elementor-widget-heading\" data-id=\"0c15841\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">what our customers say about us<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2a6270 elementor-widget elementor-widget-li-widgets--sst-slider\" data-id=\"e2a6270\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"li-widgets--sst-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- Slider main container -->\n<div class=\"li-widgets--sst-slider swiper-container\">\n    <!-- Additional required wrapper -->\n    <div class=\"swiper-wrapper\">\n        <!-- Slides -->\n                        <div class=\"swiper-slide\">\n                    \t\t<div data-elementor-type=\"section\" data-elementor-id=\"9111\" class=\"elementor elementor-9111\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10b7f7dd elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10b7f7dd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-349fd89a\" data-id=\"349fd89a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1201c8c7 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default\" data-id=\"1201c8c7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-57ce10dd\" data-id=\"57ce10dd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7190e8d7 elementor-widget elementor-widget-image\" data-id=\"7190e8d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"764\" height=\"473\" src=\"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2021\/02\/shop-apotheke-764x473-1.jpg\" class=\"attachment-large size-large wp-image-846\" alt=\"\" srcset=\"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2021\/02\/shop-apotheke-764x473-1.jpg 764w, https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2021\/02\/shop-apotheke-764x473-1-300x186.jpg 300w\" sizes=\"(max-width: 764px) 100vw, 764px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-706f5164 slider--content-column\" data-id=\"706f5164\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1faa28d6 elementor-widget elementor-widget-image\" data-id=\"1faa28d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"390\" height=\"129\" src=\"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2021\/02\/shop-apotheke-logo-1.png\" class=\"attachment-large size-large wp-image-2023\" alt=\"\" srcset=\"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2021\/02\/shop-apotheke-logo-1.png 390w, https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2021\/02\/shop-apotheke-logo-1-300x99.png 300w\" sizes=\"(max-width: 390px) 100vw, 390px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21566fbc elementor-widget elementor-widget-text-editor\" data-id=\"21566fbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The direct and cooperative partnership with CELUM has helped us to digitalize our processes even further. In doing so, we could greatly increase employee satisfaction and significantly improve our time-to-market.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1f845a74 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f845a74\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-250784ad\" data-id=\"250784ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52e7c639 elementor-widget elementor-widget-image\" data-id=\"52e7c639\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2021\/02\/dominik-wollenschein.1024x1024-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-856\" alt=\"\" srcset=\"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2021\/02\/dominik-wollenschein.1024x1024-150x150.jpg 150w, https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2021\/02\/dominik-wollenschein.1024x1024-300x300.jpg 300w, https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2021\/02\/dominik-wollenschein.1024x1024-768x768.jpg 768w, https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2021\/02\/dominik-wollenschein.1024x1024.jpg 1024w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5b004001\" data-id=\"5b004001\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-120892c2 elementor-widget elementor-widget-heading\" data-id=\"120892c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Dominik Wollenschein<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7dcb958b elementor-widget elementor-widget-heading\" data-id=\"7dcb958b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Senior Consultant, Architecture Management<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fd4a718 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"7fd4a718\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.celum.com\/en\/blog\/success-story-shop-apotheke-europe\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Read success story<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t                <\/div>\n                                <div class=\"swiper-slide\">\n                    \t\t<div data-elementor-type=\"section\" data-elementor-id=\"9111\" class=\"elementor elementor-9111\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10b7f7dd elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10b7f7dd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-349fd89a\" data-id=\"349fd89a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1201c8c7 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default\" data-id=\"1201c8c7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-57ce10dd\" data-id=\"57ce10dd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7190e8d7 elementor-widget elementor-widget-image\" data-id=\"7190e8d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"478\" src=\"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2021\/11\/sartorius-0342-pg12-data-1024x612.jpg\" class=\"attachment-large size-large wp-image-14209\" alt=\"Sartorius\" srcset=\"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2021\/11\/sartorius-0342-pg12-data-1024x612.jpg 1024w, https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2021\/11\/sartorius-0342-pg12-data-300x179.jpg 300w, https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2021\/11\/sartorius-0342-pg12-data-768x459.jpg 768w, https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2021\/11\/sartorius-0342-pg12-data-1536x918.jpg 1536w, https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2021\/11\/sartorius-0342-pg12-data-2048x1224.jpg 2048w, https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2021\/11\/sartorius-0342-pg12-data-1920x1148.jpg 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-706f5164 slider--content-column\" data-id=\"706f5164\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1faa28d6 elementor-widget elementor-widget-image\" data-id=\"1faa28d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2021\/11\/Sartorius-Logo-RGB-Positiv.svg\" class=\"attachment-large size-large wp-image-14212\" alt=\"Sartorius-Logo\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21566fbc elementor-widget elementor-widget-text-editor\" data-id=\"21566fbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>CELUM is our web-based single source of truth, and with its APIs we were able to build realtime automated integrations into other Sartorius platforms like our website sartorius.com, our eShop and the PIM system.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1f845a74 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f845a74\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-250784ad\" data-id=\"250784ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52e7c639 elementor-widget elementor-widget-image\" data-id=\"52e7c639\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2021\/02\/cropped-favicon-512x512-1-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-1931\" alt=\"\" srcset=\"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2021\/02\/cropped-favicon-512x512-1-150x150.png 150w, https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2021\/02\/cropped-favicon-512x512-1-300x300.png 300w, https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2021\/02\/cropped-favicon-512x512-1.png 512w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5b004001\" data-id=\"5b004001\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-120892c2 elementor-widget elementor-widget-heading\" data-id=\"120892c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Franziska Lis<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7dcb958b elementor-widget elementor-widget-heading\" data-id=\"7dcb958b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Product Owner eBusiness Platforms<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fd4a718 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"7fd4a718\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.celum.com\/en\/blog\/success-story-sartorius\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Read success story<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t                <\/div>\n                    <\/div>\n    <!-- If we need pagination -->\n    <div class=\"swiper-pagination\"><\/div>\n\n    <!-- If we need navigation buttons -->\n    <div class=\"slider-button swiper-button-prev\"><\/div>\n    <div class=\"slider-button swiper-button-next\"><\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ba0748a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ba0748a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ab0055e\" data-id=\"ab0055e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25abac6 elementor-star-rating--align-start elementor--star-style-star_fontawesome elementor-widget elementor-widget-star-rating\" data-id=\"25abac6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"star-rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-star-rating__wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-star-rating__title\">Based on reviews on<\/div>\n\t\t\t\t\t\t<div class=\"elementor-star-rating\" itemtype=\"http:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t\t<i class=\"elementor-star-full\" aria-hidden=\"true\">&#xE933;<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">&#xE933;<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">&#xE933;<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">&#xE933;<\/i><i class=\"elementor-star-5\" aria-hidden=\"true\">&#xE933;<\/i>\t\t\t\t<span itemprop=\"ratingValue\" class=\"elementor-screen-only\">Rated 4.5 out of 5<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ae8dd04 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ae8dd04\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-fcd8f0e\" data-id=\"fcd8f0e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37841ec elementor-widget elementor-widget-image\" data-id=\"37841ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.g2.com\/products\/celum\/reviews\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"711\" height=\"731\" src=\"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2022\/02\/g2-seeklogo.com_.svg\" class=\"attachment-full size-full wp-image-17130\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1c8f37a\" data-id=\"1c8f37a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-594ec8e elementor-widget elementor-widget-image\" data-id=\"594ec8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.capterra.com\/p\/60808\/CELUM-Digital-Asset-Management\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2022\/02\/capterra-inc-vector-logo.svg\" class=\"attachment-large size-large wp-image-17131\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b249a3e\" data-id=\"b249a3e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f29c9a elementor-widget elementor-widget-image\" data-id=\"3f29c9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/omr.com\/de\/reviews\/product\/celum\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2022\/02\/OMR_Logo_svg.svg\" class=\"attachment-large size-large wp-image-17129\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Build brand equity \u2013 tell your brand story to inspire employees, ecosystem and, most importantly, customers.<\/p>\n","protected":false},"author":7,"featured_media":39951,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"folder":[146],"class_list":["post-45357","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.6 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Manage brands and their stories<\/title>\n<meta name=\"description\" content=\"Build brand equity \u2013 tell your brand story to inspire employees, ecosystem and, most importantly, customers.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.celum.com\/en\/manage-brands-and-their-stories\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manage brands and their stories\" \/>\n<meta property=\"og:description\" content=\"Build brand equity \u2013 tell your brand story to inspire employees, ecosystem and, most importantly, customers.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.celum.com\/en\/manage-brands-and-their-stories\/\" \/>\n<meta property=\"og:site_name\" content=\"Celum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/celumcorporate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-30T14:30:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2024\/05\/IMG_Brand_Management_illustration_Primary_blue@2x.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2401\" \/>\n\t<meta property=\"og:image:height\" content=\"1261\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CELUM\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.celum.com\\\/en\\\/manage-brands-and-their-stories\\\/\",\"url\":\"https:\\\/\\\/www.celum.com\\\/en\\\/manage-brands-and-their-stories\\\/\",\"name\":\"Manage brands and their stories\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.celum.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.celum.com\\\/en\\\/manage-brands-and-their-stories\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.celum.com\\\/en\\\/manage-brands-and-their-stories\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.celum.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/05\\\/IMG_Brand_Management_illustration_Primary_blue@2x.png\",\"datePublished\":\"2025-05-19T08:18:21+00:00\",\"dateModified\":\"2025-12-30T14:30:58+00:00\",\"description\":\"Build brand equity \u2013 tell your brand story to inspire employees, ecosystem and, most importantly, customers.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.celum.com\\\/en\\\/manage-brands-and-their-stories\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.celum.com\\\/en\\\/manage-brands-and-their-stories\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.celum.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/05\\\/IMG_Brand_Management_illustration_Primary_blue@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.celum.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/05\\\/IMG_Brand_Management_illustration_Primary_blue@2x.png\",\"width\":2401,\"height\":1261,\"caption\":\"Manage your brand identity across channels and audiences with CELUM. Learn how to build a unified brand experience that sets you apart from the competitiion.\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.celum.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.celum.com\\\/en\\\/\",\"name\":\"CELUM\",\"description\":\"Make Brands. Sell Products.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.celum.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.celum.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.celum.com\\\/en\\\/#organization\",\"name\":\"CELUM\",\"url\":\"https:\\\/\\\/www.celum.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.celum.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.celum.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/celum-header-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.celum.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/celum-header-logo.svg\",\"width\":1,\"height\":1,\"caption\":\"CELUM\"},\"image\":{\"@id\":\"https:\\\/\\\/www.celum.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/celumcorporate\\\/\",\"https:\\\/\\\/x.com\\\/CELUM\",\"https:\\\/\\\/www.instagram.com\\\/celum_life\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/328144\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/celumTV\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Manage brands and their stories","description":"Build brand equity \u2013 tell your brand story to inspire employees, ecosystem and, most importantly, customers.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.celum.com\/en\/manage-brands-and-their-stories\/","og_locale":"en_US","og_type":"article","og_title":"Manage brands and their stories","og_description":"Build brand equity \u2013 tell your brand story to inspire employees, ecosystem and, most importantly, customers.","og_url":"https:\/\/www.celum.com\/en\/manage-brands-and-their-stories\/","og_site_name":"Celum","article_publisher":"https:\/\/www.facebook.com\/celumcorporate\/","article_modified_time":"2025-12-30T14:30:58+00:00","og_image":[{"width":2401,"height":1261,"url":"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2024\/05\/IMG_Brand_Management_illustration_Primary_blue@2x.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@CELUM","twitter_misc":{"Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.celum.com\/en\/manage-brands-and-their-stories\/","url":"https:\/\/www.celum.com\/en\/manage-brands-and-their-stories\/","name":"Manage brands and their stories","isPartOf":{"@id":"https:\/\/www.celum.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.celum.com\/en\/manage-brands-and-their-stories\/#primaryimage"},"image":{"@id":"https:\/\/www.celum.com\/en\/manage-brands-and-their-stories\/#primaryimage"},"thumbnailUrl":"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2024\/05\/IMG_Brand_Management_illustration_Primary_blue@2x.png","datePublished":"2025-05-19T08:18:21+00:00","dateModified":"2025-12-30T14:30:58+00:00","description":"Build brand equity \u2013 tell your brand story to inspire employees, ecosystem and, most importantly, customers.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.celum.com\/en\/manage-brands-and-their-stories\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.celum.com\/en\/manage-brands-and-their-stories\/#primaryimage","url":"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2024\/05\/IMG_Brand_Management_illustration_Primary_blue@2x.png","contentUrl":"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2024\/05\/IMG_Brand_Management_illustration_Primary_blue@2x.png","width":2401,"height":1261,"caption":"Manage your brand identity across channels and audiences with CELUM. Learn how to build a unified brand experience that sets you apart from the competitiion."},{"@type":"WebSite","@id":"https:\/\/www.celum.com\/en\/#website","url":"https:\/\/www.celum.com\/en\/","name":"CELUM","description":"Make Brands. Sell Products.","publisher":{"@id":"https:\/\/www.celum.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.celum.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.celum.com\/en\/#organization","name":"CELUM","url":"https:\/\/www.celum.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.celum.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2021\/01\/celum-header-logo.svg","contentUrl":"https:\/\/www.celum.com\/en\/wp-content\/uploads\/sites\/2\/2021\/01\/celum-header-logo.svg","width":1,"height":1,"caption":"CELUM"},"image":{"@id":"https:\/\/www.celum.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/celumcorporate\/","https:\/\/x.com\/CELUM","https:\/\/www.instagram.com\/celum_life\/","https:\/\/www.linkedin.com\/company\/328144\/","https:\/\/www.youtube.com\/user\/celumTV\/"]}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.celum.com\/en\/wp-json\/wp\/v2\/pages\/45357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.celum.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.celum.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.celum.com\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.celum.com\/en\/wp-json\/wp\/v2\/comments?post=45357"}],"version-history":[{"count":20,"href":"https:\/\/www.celum.com\/en\/wp-json\/wp\/v2\/pages\/45357\/revisions"}],"predecessor-version":[{"id":50500,"href":"https:\/\/www.celum.com\/en\/wp-json\/wp\/v2\/pages\/45357\/revisions\/50500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.celum.com\/en\/wp-json\/wp\/v2\/media\/39951"}],"wp:attachment":[{"href":"https:\/\/www.celum.com\/en\/wp-json\/wp\/v2\/media?parent=45357"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/www.celum.com\/en\/wp-json\/wp\/v2\/folder?post=45357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}